{"id":27827,"date":"2024-12-26T17:55:53","date_gmt":"2024-12-26T15:55:53","guid":{"rendered":"https:\/\/uae.mosesexport.com\/moses-granular-soolakristallid\/"},"modified":"2026-02-03T14:02:04","modified_gmt":"2026-02-03T12:02:04","slug":"moses-granular-soolakristallid","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/et\/soola\/sool-vee-tootlemiseks\/noudepesumasina-sool\/moses-granular-soolakristallid\/","title":{"rendered":"GRANULAARSED, soolakristallid"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27827\" class=\"elementor elementor-27827 elementor-17014\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5451f6 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"d5451f6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b4f4eef animated-fast elementor-invisible\" data-id=\"b4f4eef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f0a0e7 start elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wdt-heading\" data-id=\"5f0a0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-5f0a0e7\"><div class=\"wdt-heading-content-wrapper\">GRANULAARSED, soolakristallid<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-890f0d2 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"890f0d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>MOSES\u00ae GRANULAR tagab usaldusv\u00e4\u00e4rse veepehmendamise ja s\u00e4ravpuhtad n\u00f5udepesuvahendid, mist\u00f5ttu sobib see nii granuleeritud soolalahusega veepehmendajatele kui ka igat t\u00fc\u00fcpi n\u00f5udepesumasinale. Erinevalt keemiliselt puhastatud ja pressitud alternatiividest on see 100% looduslik toode, mis ei sisalda kunstlikke lisaaineid, n\u00e4iteks paakumisvastaseid aineid, tagades puhta j\u00f5udluse ja j\u00e4rjepidevad tulemused.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f616bc wdt-cus-grid-img-counter\" data-wdt-settings=\"{&quot;id&quot;:&quot;0f616bc&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"0f616bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b456b1c elementor-widget elementor-widget-image\" data-id=\"b456b1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-1024x1024.webp\" class=\"attachment-large size-large wp-image-34169\" alt=\"GRANULAARSED, soolakristallid\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-1024x1024.webp 1024w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-scaled-1000x1000.webp 1000w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-scaled-100x100.webp 100w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-300x300.webp 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-150x150.webp 150w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-768x768.webp 768w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-1536x1536.webp 1536w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/5-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8b099c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8b099c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-765a264\" data-id=\"765a264\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a611f6f elementor-widget elementor-widget-spacer\" data-id=\"a611f6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e88e51 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5e88e51\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41c3e57\" data-wdt-settings=\"{&quot;id&quot;:&quot;41c3e57&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"41c3e57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e6752a start elementor-widget-mobile__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"4e6752a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-4e6752a\"><div class=\"wdt-heading-content-wrapper\">Moses\u00ae puhta ja loodusliku veepehmendaja soolakristallid on valmistatud k\u00f5rge puhtusastmega looduslikust soolast ning pakuvad t\u00f5husat lahendust k\u00f5va veega majapidamistele. Moses\u00ae GRANULAR sobib nii kodumajapidamistele kui ka t\u00f6\u00f6stuslikele veepehmenduss\u00fcsteemidele, mis kasutavad granuleeritud soola, ning seda saab ohutult kasutada ka igat t\u00fc\u00fcpi n\u00f5udepesumasinates.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d63f49b animated-fast elementor-invisible\" data-id=\"d63f49b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f32e98d start wdt-cus-about1-iconbox wdt-cus-about1-iconbox-top elementor-widget__width-initial elementor-widget elementor-widget-wdt-icon-box\" data-id=\"f32e98d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#EDEDED&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#54595F&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;1&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-content-aside\" id=\"wdt-icon-box-f32e98d\" data-settings=\"\"><div class=\"wdt-column-wrapper wdt-column-gap-custom \" data-column-settings=\"\" data-module-id=\"wdt-module-id-f32e98d\" id=\"wdt-module-id-f32e98d\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>100% looduslik toode<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Ei sisalda lisaaineid.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Hooajaline alternatiiv soolatablettidele<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">\u00d6koloogilisem ja ka parema hinna ja kvaliteedi suhtega.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>\u00dcletab k\u00f5ige rangemaid standardeid<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Toidukvaliteediga pehmendav sool.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Egiptuse kvaliteet<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Suurep\u00e4rane klienditeenindus hinna sees.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9c2c025 e-flex e-con-boxed e-con e-parent\" data-id=\"9c2c025\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba3344c wdt-cus-our-policy wdt-cus-home2-iconbox center elementor-widget elementor-widget-wdt-icon-box\" data-id=\"ba3344c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-icon-box-ba3344c\" data-id=\"ba3344c\" data-settings=\"\"><div class=\"wdt-icon-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:30,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:30,&quot;mobile&quot;:30,&quot;tablet&quot;:30}}\" id=\"wdt-icon-box-swiper-ba3344c\"><div class=\"wdt-icon-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Tera suurus<\/h5><\/div><div class=\"wdt-content-description\">3150-6000 \u00b5m<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Toorainete t\u00fc\u00fcbid<\/h5><\/div><div class=\"wdt-content-description\">Meresool - kivisool<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Pakend<\/h5><\/div><div class=\"wdt-content-description\">20 KG - 25 KG (KOTID)\n1000 KG - 1250 KG - 1500 KG (JAMBO)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Lisandid<\/h5><\/div><div class=\"wdt-content-description\">Saadaval ilma lisanditeta<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Ladustamine<\/h5><\/div><div class=\"wdt-content-description\">Hoida kuivas kohas<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Saadetis<\/h5><\/div><div class=\"wdt-content-description\">Haagisveok<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-ba3344c\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c0f66f e-flex e-con-boxed e-con e-parent\" data-id=\"6c0f66f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d277c96 elementor-widget elementor-widget-text-editor\" data-id=\"d277c96\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"quote-section\">\n  <h3>Request a Quote<\/h3>\n  <div class=\"packaging-selector\">\n    <label for=\"product-packaging\">Select Packaging:<\/label>\n    <select id=\"product-packaging\">\n      <option value=\"\">Choose packaging<\/option>\n      <option>5 KG BAG<\/option>\n      <option>10 KG BAG<\/option>\n      <option>20 KG BAG<\/option>\n      <option>25 KG BAG<\/option>\n      <option>1000 KG JUMBO<\/option>\n      <option>1250 KG JUMBO<\/option>\n      <option>1500 KG JUMBO<\/option>\n    <\/select>\n  <\/div>\n  <button id=\"get-quote-btn\" class=\"quote-button\">Get Quote<\/button>\n<\/div>\n\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", () => {\n  const quoteBtn = document.getElementById(\"get-quote-btn\");\n  const packagingSelect = document.getElementById(\"product-packaging\");\n\n  quoteBtn.addEventListener(\"click\", () => {\n    const packaging = packagingSelect.value.trim();\n   \/\/ if (!packaging) {\n    \/\/  alert(\"Please select a packaging option first.\");\n \/\/    return;\n  \/\/  }\n\n    \/\/ Get the full title tag content and extract only the part before |\n    const pageTitle = document.title.trim();\n    const saltType = pageTitle.split('|')[0].trim();\n\n    \/\/ Detect product category based on the salt type\n    const productCategory = detectProductCategoryFromSaltType(saltType);\n\n    \/\/ Encode everything as Base64 to avoid URL encoding issues\n    const saltTypeBase64 = btoa(unescape(encodeURIComponent(saltType)));\n    const productCategoryBase64 = btoa(unescape(encodeURIComponent(productCategory)));\n    const packagingBase64 = btoa(unescape(encodeURIComponent(packaging)));\n\n    const params = new URLSearchParams({\n      packaging_b64: packagingBase64,\n      'product-category_b64': productCategoryBase64,\n      salttype_b64: saltTypeBase64\n    });\n\n    console.log('Redirecting with params:', {\n      packaging: packaging,\n      productCategory: productCategory,\n      saltType: saltType\n    });\n\n    \/\/ Redirect safely to request quote page\n    window.location.href = `\/price-enquiry\/?${params.toString()}`;\n  });\n\n  function detectProductCategoryFromSaltType(saltType) {\n    const productCategoryMap = [\n      [\/MOSES\u00ae REGULAR, salt tablets|MOSES\u00ae CRYSTALS, salt crystals\/i, \"Salt For Water Softening\"],\n      [\/MOSES\u00ae GRANULAR, Salt\/i, \"Dishwasher Salt\"],\n      [\/MOSES\u00ae REGULAR, Salt Tablets|MOSES\u00ae Swimming Pool Salt\/i, \"Swimming Pool Salt\"],\n      [\/MOSES\u00ae1-3, salt for animal feed and for agriculture|MOSES\u00ae 2-4, salt for agriculture\/i, \"Agricultural salt\"],\n      [\/MOSES\u00ae Fine Salt|MOSES\u00ae Coarse Salt|MOSES\u00ae fleur de sel\/i, \"Sea Salt! For The Food Service Sector\"],\n      [\/Moses\u00ae 0-1 Fine Road Salt|MOSES\u00ae 1-4, Coarse Road Salt|MOSES ROAD SALT\u00ae de-icing salt\/i, \"Road Salt\"],\n      [\/Moses\u00ae 0-1, fine salt|MOSES\u00ae 1-3, medium coarse salt|MOSES\u00ae 2-4, coarse salt|MOSES\u00ae 4-6, extra coarse salt|MOSES\u00ae 4-15, extra coarse salt|MOSES 6-15, extra coarse technical salt\/i, \"Industrial Salt\"],\n      [\/MOSES\u00ae 0-0.2, extra fine sea salt|MOSES\u00ae 0.2-0.8, fine sea salt|MOSES\u00ae 0-1, fine sea salt|MOSES\u00ae 0.8-1, medium fine sea salt|MOSES\u00ae 0.8-1.2, medium fine sea salt|MOSES\u00ae 1-2, medium coarse sea salt|MOSES\u00ae 1-3, medium coarse sea salt|MOSES\u00ae 1-4, coarse sea salt|MOSES\u00ae 2-4, coarse sea salt|MOSES\u00ae 4-6, extra coarse sea salt|MOSES\u00ae 4-15, extra coarse sea salt\/i, \"Salt To Taste\"],\n      [\/MOSES1-3, salt for animal feed and for agriculture|MOSES,Salt Block\/i, \"Salt for animal feed\"]\n    ];\n    \n    for (const [regex, productCategory] of productCategoryMap) {\n      if (regex.test(saltType)) {\n        console.log('Detected product category:', productCategory, 'for salt type:', saltType);\n        return productCategory;\n      }\n    }\n    \n    \/\/ Default fallback if no match found\n    console.log('No product category match found, using default: Select Product category');\n    return \"Select Product category\";\n  }\n});\n<\/script>\n\n<style>\n.quote-section {\n  background: #f9f9f9;\n  padding: 20px;\n  margin: 20px 0;\n  border-radius: 8px;\n  border: 1px solid #ddd;\n}\n.packaging-selector label {\n  font-weight: 600;\n  margin-bottom: 5px;\n  display: block;\n}\n.packaging-selector select, .quote-button {\n  padding: 10px;\n  border-radius: 4px;\n  border: 1px solid #ccc;\n  font-size: 15px;\n}\n.quote-button {\n  background: #007cba;\n  color: #fff;\n  border: none;\n  cursor: pointer;\n  font-weight: bold;\n  margin-top: 10px;\n}\n.quote-button:hover {\n  background: #005a87;\n}\n<\/style><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9911307 e-flex e-con-boxed e-con e-parent\" data-id=\"9911307\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d98af20 elementor-widget elementor-widget-heading\" data-id=\"d98af20\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/uae.mosesexport.com\/et\/noudepesumasina-sool\/\">MOSES\u00ae n\u00f5udepesumasina sool<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f120bf6 elementor-widget elementor-widget-text-editor\" data-id=\"f120bf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>N\u00f5udepesumasina soola kasutatakse n\u00f5udepesumasina ioonvaheti vaigu uuendamiseks, et see saaks vett pehmendada. See suurendab puhastusj\u00f5udlust, mis tagab suurep\u00e4rased pesutulemused ja kaitseb n\u00f5udepesumasinat katlakivi ladestumise eest. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>GRANULAARSED, soolakristallid MOSES\u00ae GRANULAR tagab usaldusv\u00e4\u00e4rse veepehmendamise ja s\u00e4ravpuhtad n\u00f5udepesuvahendid, mist\u00f5ttu sobib see nii granuleeritud soolalahusega veepehmendajatele kui ka igat t\u00fc\u00fcpi n\u00f5udepesumasinale. Erinevalt keemiliselt puhastatud ja pressitud alternatiividest on see 100% looduslik toode, mis ei sisalda kunstlikke lisaaineid, n\u00e4iteks paakumisvastaseid aineid, tagades puhta j\u00f5udluse ja j\u00e4rjepidevad tulemused. Moses\u00ae puhta ja loodusliku veepehmendaja soolakristallid on valmistatud [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34169,"parent":25810,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27827","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/pages\/27827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/comments?post=27827"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/pages\/27827\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/pages\/25810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/media\/34169"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/et\/wp-json\/wp\/v2\/media?parent=27827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}