{"id":27884,"date":"2024-12-24T13:49:36","date_gmt":"2024-12-24T11:49:36","guid":{"rendered":"https:\/\/uae.mosesexport.com\/moses-1-3-kozepesen-durva-tengeri-so\/"},"modified":"2026-02-08T16:05:40","modified_gmt":"2026-02-08T14:05:40","slug":"moses-1-3-kozepesen-durva-tengeri-so","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-1-3-kozepesen-durva-tengeri-so\/","title":{"rendered":"1-3, medium coarse sea salt"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27884\" class=\"elementor elementor-27884 elementor-16700\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0be030 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a0be030\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-acc120b animated-fast elementor-invisible\" data-id=\"acc120b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e6ee86 start elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wdt-heading\" data-id=\"3e6ee86\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-3e6ee86\"><div class=\"wdt-heading-content-wrapper\">MOSES\u00ae 1-3, k\u00f6zepesen durva tengeri s\u00f3<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2588ac3 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"2588ac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A MOSES\u00ae 1-3 k\u00f6zepesen durva tengeri s\u00f3 \u00e9lelmiszeripari min\u0151s\u00e9g\u0171 tengeri s\u00f3. A k\u00f6zepes tengeri s\u00f3 krist\u00e1lym\u00e9ret ide\u00e1liss\u00e1 teszi s\u00fctem\u00e9nyek felt\u00e9teihez, sz\u00e1raz turmixokhoz, f\u0171szerekhez, h\u00fashoz, baromfihoz \u00e9s halhoz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dacfd29 wdt-cus-grid-img-counter\" data-wdt-settings=\"{&quot;id&quot;:&quot;dacfd29&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"dacfd29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5c1c8a elementor-widget elementor-widget-image\" data-id=\"b5c1c8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0628\u0644\u0648\u0631\u0627\u062a-\u0645\u0644\u062d-\u063a\u0633\u0627\u0644\u0627\u062a-\u0627\u0644\u0627\u0637\u0628\u0627\u0642.png\" class=\"attachment-large size-large wp-image-26175\" alt=\"k\u00f6zepesen durva tengeri s\u00f3\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0628\u0644\u0648\u0631\u0627\u062a-\u0645\u0644\u062d-\u063a\u0633\u0627\u0644\u0627\u062a-\u0627\u0644\u0627\u0637\u0628\u0627\u0642.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0628\u0644\u0648\u0631\u0627\u062a-\u0645\u0644\u062d-\u063a\u0633\u0627\u0644\u0627\u062a-\u0627\u0644\u0627\u0637\u0628\u0627\u0642-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0628\u0644\u0648\u0631\u0627\u062a-\u0645\u0644\u062d-\u063a\u0633\u0627\u0644\u0627\u062a-\u0627\u0644\u0627\u0637\u0628\u0627\u0642-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0628\u0644\u0648\u0631\u0627\u062a-\u0645\u0644\u062d-\u063a\u0633\u0627\u0644\u0627\u062a-\u0627\u0644\u0627\u0637\u0628\u0627\u0642-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67b306c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67b306c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dba9a9\" data-id=\"9dba9a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f0c55c elementor-widget elementor-widget-spacer\" data-id=\"1f0c55c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c723268 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c723268\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f2677e5\" data-wdt-settings=\"{&quot;id&quot;:&quot;f2677e5&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"f2677e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-080a347 start elementor-widget elementor-widget-wdt-heading\" data-id=\"080a347\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-080a347\"><div class=\"wdt-heading-content-wrapper\">A MOSES\u00ae 1-3 t\u00f6k\u00e9letesen alkalmas olyan alkalmaz\u00e1sokhoz, ahol a s\u00f3 j\u00f3l l\u00e1that\u00f3 marad a v\u00e9gfelhaszn\u00e1l\u00f3 sz\u00e1m\u00e1ra. Gyakran haszn\u00e1lj\u00e1k s\u00f3dar\u00e1l\u00f3kban, f\u0171szer- \u00e9s gy\u00f3gyn\u00f6v\u00e9nykever\u00e9kekben, valamint halak \u00e9s egy\u00e9b \u00e9telek t\u00e1lal\u00e1s\u00e1nak fokoz\u00e1s\u00e1ra. Nagy tisztas\u00e1g\u00e1nak \u00e9s pontosan szab\u00e1lyozott szemcsem\u00e9ret-eloszl\u00e1s\u00e1nak k\u00f6sz\u00f6nhet\u0151en ez a pr\u00e9mium tengeri s\u00f3 kiv\u00e1l\u00f3an alkalmas s\u00f3l\u00e9 el\u0151\u00e1ll\u00edt\u00e1s\u00e1ra is.\n\nA kulin\u00e1ris alkalmaz\u00e1sokon t\u00fal a MOSES\u00ae 1-3-at gyakran haszn\u00e1lj\u00e1k f\u00fcrd\u0151s\u00f3k\u00e9nt, amelyet min\u0151s\u00e9ge \u00e9s \u00e1llaga miatt \u00e9rt\u00e9kelnek.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e61fa03 animated-fast elementor-invisible\" data-id=\"e61fa03\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f819ea2 start wdt-cus-about1-iconbox wdt-cus-about1-iconbox-top elementor-widget__width-initial elementor-widget elementor-widget-wdt-icon-box\" data-id=\"f819ea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#EDEDED&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#54595F&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;1&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-content-aside\" id=\"wdt-icon-box-f819ea2\" data-settings=\"\"><div class=\"wdt-column-wrapper wdt-column-gap-custom \" data-column-settings=\"\" data-module-id=\"wdt-module-id-f819ea2\" id=\"wdt-module-id-f819ea2\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>A legmagasabb \u00e9lelmiszeripari min\u0151s\u00e9g\u0171 (99,8% NaCl)<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Sz\u00f3 szerint minden egyes gabon\u00e1t ellen\u0151riznek tisztas\u00e1g szempontj\u00e1b\u00f3l.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Term\u00e9szetes term\u00e9k<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Emeld ki a tengeri s\u00f3 term\u00e9szetes tulajdons\u00e1gait az \u00fcgyf\u00e9lkommunik\u00e1ci\u00f3dban.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>E-sz\u00e1mok n\u00e9lk\u00fcli s\u00f3<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">T\u00f6k\u00e9letes mind a hagyom\u00e1nyos, mind az \u00f6kol\u00f3giai termel\u00e9si sorokhoz.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>\u00c1sv\u00e1nyi anyagokban \u00e9s nyomelemekben gazdag<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Test\u00e1pol\u00e1si alapkell\u00e9kek.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e8375e7 e-flex e-con-boxed e-con e-parent\" data-id=\"e8375e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12e77ba wdt-cus-our-policy wdt-cus-home2-iconbox center elementor-widget elementor-widget-wdt-icon-box\" data-id=\"12e77ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-icon-box-12e77ba\" data-id=\"12e77ba\" data-settings=\"\"><div class=\"wdt-icon-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:30,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:30,&quot;mobile&quot;:30,&quot;tablet&quot;:30}}\" id=\"wdt-icon-box-swiper-12e77ba\"><div class=\"wdt-icon-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Szemcsem\u00e9ret<\/h5><\/div><div class=\"wdt-content-description\">1000-3500 \u00b5m\n\n<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Nyersanyagok t\u00edpusai<\/h5><\/div><div class=\"wdt-content-description\">Tengeri s\u00f3 - K\u0151s\u00f3<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Csomagol\u00e1s<\/h5><\/div><div class=\"wdt-content-description\">5KG - 10 KG - 20 KG - 25KG (ZS\u00c1KOK)\n1000KG - 1250KG - 1500KG (JAMBO)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>adal\u00e9kanyagok<\/h5><\/div><div class=\"wdt-content-description\">Adal\u00e9kanyagok n\u00e9lk\u00fcl kaphat\u00f3<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>T\u00e1rol\u00e1s<\/h5><\/div><div class=\"wdt-content-description\">Sz\u00e1raz helyen t\u00e1roland\u00f3<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Sz\u00e1ll\u00edt\u00e1s<\/h5><\/div><div class=\"wdt-content-description\">P\u00f3tkocsis teheraut\u00f3<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-12e77ba\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c170385 e-flex e-con-boxed e-con e-parent\" data-id=\"c170385\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97daf1f elementor-widget elementor-widget-text-editor\" data-id=\"97daf1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"quote-section\">\n  <h3>Request a Quote<\/h3>\n  <div class=\"packaging-selector\">\n    <label for=\"product-packaging\">Select Packaging:<\/label>\n    <select id=\"product-packaging\">\n      <option value=\"\">Choose packaging<\/option>\n      <option>5 KG BAG<\/option>\n      <option>10 KG BAG<\/option>\n      <option>20 KG BAG<\/option>\n      <option>25 KG BAG<\/option>\n      <option>1000 KG JUMBO<\/option>\n      <option>1250 KG JUMBO<\/option>\n      <option>1500 KG JUMBO<\/option>\n    <\/select>\n  <\/div>\n  <button id=\"get-quote-btn\" class=\"quote-button\">Get Quote<\/button>\n<\/div>\n\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", () => {\n  const quoteBtn = document.getElementById(\"get-quote-btn\");\n  const packagingSelect = document.getElementById(\"product-packaging\");\n\n  quoteBtn.addEventListener(\"click\", () => {\n    const packaging = packagingSelect.value.trim();\n   \/\/ if (!packaging) {\n    \/\/  alert(\"Please select a packaging option first.\");\n \/\/    return;\n  \/\/  }\n\n    \/\/ Get the full title tag content and extract only the part before |\n    const pageTitle = document.title.trim();\n    const saltType = pageTitle.split('|')[0].trim();\n\n    \/\/ Detect product category based on the salt type\n    const productCategory = detectProductCategoryFromSaltType(saltType);\n\n    \/\/ Encode everything as Base64 to avoid URL encoding issues\n    const saltTypeBase64 = btoa(unescape(encodeURIComponent(saltType)));\n    const productCategoryBase64 = btoa(unescape(encodeURIComponent(productCategory)));\n    const packagingBase64 = btoa(unescape(encodeURIComponent(packaging)));\n\n    const params = new URLSearchParams({\n      packaging_b64: packagingBase64,\n      'product-category_b64': productCategoryBase64,\n      salttype_b64: saltTypeBase64\n    });\n\n    console.log('Redirecting with params:', {\n      packaging: packaging,\n      productCategory: productCategory,\n      saltType: saltType\n    });\n\n    \/\/ Redirect safely to request quote page\n    window.location.href = `\/price-enquiry\/?${params.toString()}`;\n  });\n\n  function detectProductCategoryFromSaltType(saltType) {\n    const productCategoryMap = [\n      [\/MOSES\u00ae REGULAR, salt tablets|MOSES\u00ae CRYSTALS, salt crystals\/i, \"Salt For Water Softening\"],\n      [\/MOSES\u00ae GRANULAR, Salt\/i, \"Dishwasher Salt\"],\n      [\/MOSES\u00ae REGULAR, Salt Tablets|MOSES\u00ae Swimming Pool Salt\/i, \"Swimming Pool Salt\"],\n      [\/MOSES\u00ae1-3, salt for animal feed and for agriculture|MOSES\u00ae 2-4, salt for agriculture\/i, \"Agricultural salt\"],\n      [\/MOSES\u00ae Fine Salt|MOSES\u00ae Coarse Salt|MOSES\u00ae fleur de sel\/i, \"Sea Salt! For The Food Service Sector\"],\n      [\/Moses\u00ae 0-1 Fine Road Salt|MOSES\u00ae 1-4, Coarse Road Salt|MOSES ROAD SALT\u00ae de-icing salt\/i, \"Road Salt\"],\n      [\/Moses\u00ae 0-1, fine salt|MOSES\u00ae 1-3, medium coarse salt|MOSES\u00ae 2-4, coarse salt|MOSES\u00ae 4-6, extra coarse salt|MOSES\u00ae 4-15, extra coarse salt|MOSES 6-15, extra coarse technical salt\/i, \"Industrial Salt\"],\n      [\/MOSES\u00ae 0-0.2, extra fine sea salt|MOSES\u00ae 0.2-0.8, fine sea salt|MOSES\u00ae 0-1, fine sea salt|MOSES\u00ae 0.8-1, medium fine sea salt|MOSES\u00ae 0.8-1.2, medium fine sea salt|MOSES\u00ae 1-2, medium coarse sea salt|MOSES\u00ae 1-3, medium coarse sea salt|MOSES\u00ae 1-4, coarse sea salt|MOSES\u00ae 2-4, coarse sea salt|MOSES\u00ae 4-6, extra coarse sea salt|MOSES\u00ae 4-15, extra coarse sea salt\/i, \"Salt To Taste\"],\n      [\/MOSES1-3, salt for animal feed and for agriculture|MOSES,Salt Block\/i, \"Salt for animal feed\"]\n    ];\n    \n    for (const [regex, productCategory] of productCategoryMap) {\n      if (regex.test(saltType)) {\n        console.log('Detected product category:', productCategory, 'for salt type:', saltType);\n        return productCategory;\n      }\n    }\n    \n    \/\/ Default fallback if no match found\n    console.log('No product category match found, using default: Select Product category');\n    return \"Select Product category\";\n  }\n});\n<\/script>\n\n<style>\n.quote-section {\n  background: #f9f9f9;\n  padding: 20px;\n  margin: 20px 0;\n  border-radius: 8px;\n  border: 1px solid #ddd;\n}\n.packaging-selector label {\n  font-weight: 600;\n  margin-bottom: 5px;\n  display: block;\n}\n.packaging-selector select, .quote-button {\n  padding: 10px;\n  border-radius: 4px;\n  border: 1px solid #ccc;\n  font-size: 15px;\n}\n.quote-button {\n  background: #007cba;\n  color: #fff;\n  border: none;\n  cursor: pointer;\n  font-weight: bold;\n  margin-top: 10px;\n}\n.quote-button:hover {\n  background: #005a87;\n}\n<\/style><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f197c5 e-flex e-con-boxed e-con e-parent\" data-id=\"7f197c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a3bca0 elementor-widget__width-inherit elementor-widget elementor-widget-n-accordion\" data-id=\"0a3bca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1070\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1070\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> DATA SHEETS <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1070\" class=\"elementor-element elementor-element-f5dee2f e-con-full e-flex e-con e-child\" data-id=\"f5dee2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1070\" class=\"elementor-element elementor-element-cf83ab0 e-con-full e-flex e-con e-child\" data-id=\"cf83ab0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae94897 elementor-widget elementor-widget-image\" data-id=\"ae94897\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/02\/pdf_icon-1.svg\" class=\"attachment-large size-large wp-image-37370\" alt=\"\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dba1fc elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6dba1fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>k\u00f6zepesen durva tengeri s\u00f3 (PDS)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1070\" class=\"elementor-element elementor-element-59fcb23 e-con-full e-flex e-con e-child\" data-id=\"59fcb23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-027ca89 center elementor-widget elementor-widget-wdt-button\" data-id=\"027ca89\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-bordered wdt-button-link wdt-button-style-default wdt-button-size-sm wdt-animation- wdt-button-icon-before\" id=\"wdt-button-027ca89\"><a class=\"wdt-button\" href=\"#\"><div class=\"wdt-button-icon\"><span><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-eye\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 144a110.94 110.94 0 0 0-31.24 5 55.4 55.4 0 0 1 7.24 27 56 56 0 0 1-56 56 55.4 55.4 0 0 1-27-7.24A111.71 111.71 0 1 0 288 144zm284.52 97.4C518.29 135.59 410.93 64 288 64S57.68 135.64 3.48 241.41a32.35 32.35 0 0 0 0 29.19C57.71 376.41 165.07 448 288 448s230.32-71.64 284.52-177.41a32.35 32.35 0 0 0 0-29.19zM288 400c-98.65 0-189.09-55-237.93-144C98.91 167 189.34 112 288 112s189.09 55 237.93 144C477.1 345 386.66 400 288 400z\"><\/path><\/svg><\/span><\/div><div class=\"wdt-button-text\"><span>Preview<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1070\" class=\"elementor-element elementor-element-4f685cc e-con-full e-flex e-con e-child\" data-id=\"4f685cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c426e52 center elementor-widget elementor-widget-wdt-button\" data-id=\"c426e52\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-bordered wdt-button-link wdt-button-style-default wdt-button-size-sm wdt-animation- wdt-button-icon-before\" id=\"wdt-button-c426e52\"><a class=\"wdt-button\" href=\"#\"><div class=\"wdt-button-icon\"><span><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-share-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M352 320c-22.608 0-43.387 7.819-59.79 20.895l-102.486-64.054a96.551 96.551 0 0 0 0-41.683l102.486-64.054C308.613 184.181 329.392 192 352 192c53.019 0 96-42.981 96-96S405.019 0 352 0s-96 42.981-96 96c0 7.158.79 14.13 2.276 20.841L155.79 180.895C139.387 167.819 118.608 160 96 160c-53.019 0-96 42.981-96 96s42.981 96 96 96c22.608 0 43.387-7.819 59.79-20.895l102.486 64.054A96.301 96.301 0 0 0 256 416c0 53.019 42.981 96 96 96s96-42.981 96-96-42.981-96-96-96z\"><\/path><\/svg><\/span><\/div><div class=\"wdt-button-text\"><span>Share<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1070\" class=\"elementor-element elementor-element-51181c3 e-con-full e-flex e-con e-child\" data-id=\"51181c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54c74e6 elementor-widget__width-inherit center elementor-widget elementor-widget-wdt-button\" data-id=\"54c74e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-link wdt-button-style-default wdt-button-size-sm wdt-animation- wdt-button-icon-before\" id=\"wdt-button-54c74e6\"><a class=\"wdt-button\" href=\"#\"><div class=\"wdt-button-icon\"><span><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg><\/span><\/div><div class=\"wdt-button-text\"><span>Download<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e154644 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e154644\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_position&quot;:&quot;center left&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b540416 animated-fast elementor-invisible\" data-id=\"b540416\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b29825c elementor-widget__width-initial center elementor-widget elementor-widget-wdt-heading\" data-id=\"b29825c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-b29825c\"><div class=\"wdt-heading-content-wrapper\">Hasonl\u00f3 term\u00e9k<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9e906dd e-flex e-con-boxed e-con e-parent\" data-id=\"9e906dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f91509f wdt-cus-services-imgbox animated-fast center elementor-invisible elementor-widget elementor-widget-wdt-image-box\" data-id=\"f91509f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;5&quot;,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;100&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-image-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-custom-template\" id=\"wdt-image-box-f91509f\" data-settings=\"{&quot;enable_popup&quot;:&quot;&quot;,&quot;enable_hover_class&quot;:&quot;&quot;}\"><div class=\"wdt-column-wrapper wdt-column-gap-default wdt-snap-scroll-enabled\" data-column-settings=\"{&quot;columnDevices&quot;:[&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\" data-module-id=\"wdt-module-id-f91509f\" id=\"wdt-module-id-f91509f\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-0-1-finom-tengeri-so-2\/\"><img decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/a2ec6995cd284aeb7318468f7dbc1eb24788a3bd_Korrel_MARSEL_SALCO_0_1_1440x952px.png\" class=\"attachment-full size-full wp-image-16625\" alt=\"MOSES\u00ae 0-1, fine Coarse sea salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/a2ec6995cd284aeb7318468f7dbc1eb24788a3bd_Korrel_MARSEL_SALCO_0_1_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/a2ec6995cd284aeb7318468f7dbc1eb24788a3bd_Korrel_MARSEL_SALCO_0_1_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-0-1-finom-tengeri-so-2\/\">Moses\u00ae 0-1, finom tengeri s\u00f3<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-2-4-durva-tengeri-so\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px-1.png\" class=\"attachment-full size-full wp-image-16647\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px-1.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px-1-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px-1-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px-1-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-2-4-durva-tengeri-so\/\">MOSES\u00ae 2-4, durva tengeri s\u00f3<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-4-6-extra-durva-tengeri-so-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/0d7a1d4d232cf44b3600e62f4070a522c14b0449_Korrel_MARSEL_SALCO_VAATWASZOUT_SS_GRANULAR_4_6_1440x952px.png\" class=\"attachment-full size-full wp-image-16627\" alt=\"MOSES\u00ae 4-6, extra coarse sea salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/0d7a1d4d232cf44b3600e62f4070a522c14b0449_Korrel_MARSEL_SALCO_VAATWASZOUT_SS_GRANULAR_4_6_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/0d7a1d4d232cf44b3600e62f4070a522c14b0449_Korrel_MARSEL_SALCO_VAATWASZOUT_SS_GRANULAR_4_6_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-4-6-extra-durva-tengeri-so-2\/\">MOSES\u00ae 4-6, extra durva tengeri s\u00f3<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-4-15-extra-durva-tengeri-so\/\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/aaafb1d6a58d37e1e96890dcc17c9e63707177d5_Korrel_MARSEL_SS_CRYSTALS_5_15_1440x952px.png\" class=\"attachment-full size-full wp-image-16626\" alt=\"MOSES\u00ae 4-15, extra coarse sea salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/aaafb1d6a58d37e1e96890dcc17c9e63707177d5_Korrel_MARSEL_SS_CRYSTALS_5_15_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/aaafb1d6a58d37e1e96890dcc17c9e63707177d5_Korrel_MARSEL_SS_CRYSTALS_5_15_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-4-15-extra-durva-tengeri-so\/\">MOSES\u00ae 4-15, extra durva tengeri s\u00f3<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-6-15-extra-durva-technikai-so\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/085a38ec15df943e18bb98ae75c4e9b41b21f860_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px__1_.png\" class=\"attachment-full size-full wp-image-16583\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/085a38ec15df943e18bb98ae75c4e9b41b21f860_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px__1_.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/085a38ec15df943e18bb98ae75c4e9b41b21f860_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px__1_-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/085a38ec15df943e18bb98ae75c4e9b41b21f860_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px__1_-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/085a38ec15df943e18bb98ae75c4e9b41b21f860_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px__1_-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/hu\/so\/ipari-so\/moses-6-15-extra-durva-technikai-so\/\">MOSES 6-15, extra durva technikai s\u00f3<\/a><\/h5><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-column-pagination wdt-snap-scroll-pagination\">\n\t\t\t\t\t\t<button class=\"wdt-pagination-prev wdt-module-id-f91509f\">Previous<\/button>\n\t\t\t\t\t\t<button class=\"wdt-pagination-next wdt-module-id-f91509f\">Next<\/button><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b594725 e-flex e-con-boxed e-con e-parent\" data-id=\"b594725\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MOSES\u00ae 1-3, k\u00f6zepesen durva tengeri s\u00f3 A MOSES\u00ae 1-3 k\u00f6zepesen durva tengeri s\u00f3 \u00e9lelmiszeripari min\u0151s\u00e9g\u0171 tengeri s\u00f3. A k\u00f6zepes tengeri s\u00f3 krist\u00e1lym\u00e9ret ide\u00e1liss\u00e1 teszi s\u00fctem\u00e9nyek felt\u00e9teihez, sz\u00e1raz turmixokhoz, f\u0171szerekhez, h\u00fashoz, baromfihoz \u00e9s halhoz. A MOSES\u00ae 1-3 t\u00f6k\u00e9letesen alkalmas olyan alkalmaz\u00e1sokhoz, ahol a s\u00f3 j\u00f3l l\u00e1that\u00f3 marad a v\u00e9gfelhaszn\u00e1l\u00f3 sz\u00e1m\u00e1ra. Gyakran haszn\u00e1lj\u00e1k s\u00f3dar\u00e1l\u00f3kban, f\u0171szer- \u00e9s gy\u00f3gyn\u00f6v\u00e9nykever\u00e9kekben, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26175,"parent":26144,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27884","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/pages\/27884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/comments?post=27884"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/pages\/27884\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/pages\/26144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/media\/26175"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/hu\/wp-json\/wp\/v2\/media?parent=27884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}