{"id":21810,"date":"2025-01-05T16:01:51","date_gmt":"2025-01-05T14:01:51","guid":{"rendered":"https:\/\/uae.mosesexport.com\/moses-0-2-0-8-fijn-zeezout\/"},"modified":"2025-05-22T14:19:07","modified_gmt":"2025-05-22T11:19:07","slug":"moses-0-2-0-8-fijn-zeezout","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/nl\/zout\/zout-naar-smaak\/moses-0-2-0-8-fijn-zeezout\/","title":{"rendered":"MOSES\u00ae 0.2-0.8, fijn zeezout"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21810\" class=\"elementor elementor-21810 elementor-17430\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bea781 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"0bea781\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9d3f2bc animated-fast elementor-invisible\" data-id=\"9d3f2bc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-341f234 start elementor-widget elementor-widget-wdt-heading\" data-id=\"341f234\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-341f234\"><div class=\"wdt-heading-content-wrapper\">MOSES\u00ae 0,2-0,8, fijn zout<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e723ba wdt-cus-grid-img-counter\" data-wdt-settings=\"{&quot;id&quot;:&quot;7e723ba&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"7e723ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6607165 elementor-widget elementor-widget-image\" data-id=\"6607165\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3de0bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3de0bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f967d2e\" data-id=\"f967d2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8663f6 elementor-widget elementor-widget-spacer\" data-id=\"e8663f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eeadc1f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"eeadc1f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-94635b2\" data-wdt-settings=\"{&quot;id&quot;:&quot;94635b2&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"94635b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19abe8c start elementor-widget__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"19abe8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-19abe8c\"><div class=\"wdt-heading-content-wrapper\">Multifunctioneel zout en een ideale vervanger voor vacu\u00fcmzout. Dankzij de mooie witte kleur, hoge zuiverheid en homogeniteit doet dit zout wonderen in elk recept.\n\nIdeaal voor alle voedingsproducten waarvoor zout van goede kwaliteit vereist is: kaas, conserven, deegwaren, vlees, vis, enz.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6fa161c animated-fast elementor-invisible\" data-id=\"6fa161c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ce7c29 start wdt-cus-about1-iconbox wdt-cus-about1-iconbox-top elementor-widget__width-initial elementor-widget elementor-widget-wdt-icon-box\" data-id=\"3ce7c29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#EDEDED&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#54595F&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;1&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-content-aside\" id=\"wdt-icon-box-3ce7c29\" data-settings=\"\"><div class=\"wdt-column-wrapper wdt-column-gap-custom \" data-column-settings=\"\" data-module-id=\"wdt-module-id-3ce7c29\" id=\"wdt-module-id-3ce7c29\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>De allerhoogste voedselkwaliteit (99,8% NaCl)<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Werkelijk elk graantje wordt op zuiverheid gecontroleerd.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Natuurlijk product<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Benadruk de natuurlijke eigenschappen van zout in uw klantcommunicatie.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Rijk aan mineralen en sporenelementen<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Lichaamsbenodigdheden.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Zout zonder E-nummers<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Ideaal voor zowel conventionele als biologische productielijnen.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c2b3b8e e-flex e-con-boxed e-con e-parent\" data-id=\"c2b3b8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d6b66a wdt-cus-our-policy wdt-cus-home2-iconbox center elementor-widget elementor-widget-wdt-icon-box\" data-id=\"1d6b66a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-icon-box-1d6b66a\" data-id=\"1d6b66a\" data-settings=\"\"><div class=\"wdt-icon-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:30,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:30,&quot;mobile&quot;:30,&quot;tablet&quot;:30}}\" id=\"wdt-icon-box-swiper-1d6b66a\"><div class=\"wdt-icon-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Korrelgrootte<\/h5><\/div><div class=\"wdt-content-description\">200-800 \u00b5m\n\n\n\n<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Soorten grondstoffen<\/h5><\/div><div class=\"wdt-content-description\">Zeezout - Steenzout<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Verpakking<\/h5><\/div><div class=\"wdt-content-description\">5KG - 10 KG - 20 KG - 25KG  (BAGS)\n1000KG - 1250KG - 1500KG (JAMBO)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Additieven<\/h5><\/div><div class=\"wdt-content-description\">Verkrijgbaar zonder toevoegingen\n(Verkrijgbaar met kaliumjodaat (jodium))<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Opslag<\/h5><\/div><div class=\"wdt-content-description\">Bewaren op een droge plaats<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Verzending<\/h5><\/div><div class=\"wdt-content-description\">Aanhangwagen vrachtwagen<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-1d6b66a\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-448c7d7 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"448c7d7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_position&quot;:&quot;center left&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b567aa2 animated-fast elementor-invisible\" data-id=\"b567aa2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad3458b elementor-widget__width-initial center elementor-widget elementor-widget-wdt-heading\" data-id=\"ad3458b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-ad3458b\"><div class=\"wdt-heading-content-wrapper\">Soortgelijke artikelen<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ad7701c e-flex e-con-boxed e-con e-parent\" data-id=\"ad7701c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef226e wdt-cus-services-imgbox animated-fast elementor-widget__width-initial center elementor-invisible elementor-widget elementor-widget-wdt-image-box\" data-id=\"3ef226e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;6&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;100&quot;,&quot;marquee_class&quot;:&quot;yes&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:13,&quot;sizes&quot;:[]},&quot;overflow_type&quot;:&quot;right&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_color&quot;:&quot;#6EC1E4&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_color&quot;:&quot;#FFC527&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-image-box-holder wdt-marquee-wrapper wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-image-box-3ef226e\" data-id=\"3ef226e\" data-settings=\"{&quot;enable_popup&quot;:&quot;&quot;,&quot;enable_hover_class&quot;:&quot;&quot;}\"><div class=\"wdt-image-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;right&quot;,&quot;overflow_opacity&quot;:null,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:13,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:6,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:13,&quot;mobile&quot;:13,&quot;tablet&quot;:13}}\" id=\"wdt-image-box-swiper-3ef226e\"><div class=\"wdt-image-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-0-2-extra-fine-sea-salt\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png\" class=\"attachment-full size-full wp-image-17414\" alt=\"MOSES\u00ae 0.8-1, medium fine salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-0-2-extra-fine-sea-salt\/\">MOSES\u00ae 0-0,2, extra fijn zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-1-fine-sea-salt-2\/\"rel=\"nofollow\" ><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1.png\" class=\"attachment-full size-full wp-image-17418\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-1-fine-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 0-1, fijn zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-medium-fine-sea-salt\/\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.png\" class=\"attachment-full size-full wp-image-17416\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-medium-fine-sea-salt\/\">MOSES\u00ae 0,8-1, middelfijn zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-2-medium-fine-sea-salt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2.png\" class=\"attachment-full size-full wp-image-17415\" alt=\"MOSES\u00ae 1-2, medium coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-2-medium-fine-sea-salt\/\">MOSES\u00ae 0,8-1,2, middelfijn zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-2-medium-coarse-sea-salt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2.png\" class=\"attachment-full size-full wp-image-17419\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-2-medium-coarse-sea-salt\/\">MOSES\u00ae 1-2, middelgrof zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-3-medium-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3.png\" class=\"attachment-full size-full wp-image-17420\" alt=\"MOSES\u00ae 1-3, medium coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-3-medium-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 1-3, middelgrof zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-4-coarse-sea-salt\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4.png\" class=\"attachment-full size-full wp-image-17421\" alt=\"MOSES\u00ae 1-4, coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-4-coarse-sea-salt\/\"rel=\"nofollow\" >MOSES\u00ae 1-4, grof zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-2-4-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png\" class=\"attachment-full size-full wp-image-17422\" alt=\"MOSES\u00ae 2-4, coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-2-4-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 2-4, grof zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-4-6-extra-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6.png\" class=\"attachment-full size-full wp-image-17423\" alt=\"MOSES\u00ae 4-6, extra coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-4-6-extra-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 4-6, extra grof zout<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-4-15-extra-coarse-sea-salt-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15.png\" class=\"attachment-full size-full wp-image-17424\" alt=\"MOSES\u00ae 4-15, extra coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-4-15-extra-coarse-sea-salt-2\/\">MOSES\u00ae 4-15, extra grof zout<\/a><\/h5><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-3ef226e\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MOSES\u00ae 0,2-0,8, fijn zout Multifunctioneel zout en een ideale vervanger voor vacu\u00fcmzout. Dankzij de mooie witte kleur, hoge zuiverheid en homogeniteit doet dit zout wonderen in elk recept. Ideaal voor alle voedingsproducten waarvoor zout van goede kwaliteit vereist is: kaas, conserven, deegwaren, vlees, vis, enz. De allerhoogste voedselkwaliteit (99,8% NaCl) Werkelijk elk graantje wordt op [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31760,"parent":21799,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-21810","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/pages\/21810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/comments?post=21810"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/pages\/21810\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/pages\/21799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/media\/31760"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/nl\/wp-json\/wp\/v2\/media?parent=21810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}