{"id":21814,"date":"2025-01-05T16:03:08","date_gmt":"2025-01-05T14:03:08","guid":{"rendered":"https:\/\/uae.mosesexport.com\/moses-0-1-drobna-sol-morska\/"},"modified":"2025-05-25T12:34:49","modified_gmt":"2025-05-25T09:34:49","slug":"moses-0-1-drobna-sol-morska","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/pl\/sol\/sol-do-smaku\/moses-0-1-drobna-sol-morska\/","title":{"rendered":"MOSES\u00ae 0-1, drobna s\u00f3l morska"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21814\" class=\"elementor elementor-21814 elementor-17432\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b3f408 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"8b3f408\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52b83fd animated-fast elementor-invisible\" data-id=\"52b83fd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54527f1 start elementor-widget elementor-widget-wdt-heading\" data-id=\"54527f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-54527f1\"><div class=\"wdt-heading-content-wrapper\">MOSES\u00ae 0-1, s\u00f3l drobna\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5cf402b wdt-cus-grid-img-counter\" data-wdt-settings=\"{&quot;id&quot;:&quot;5cf402b&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"5cf402b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-664daed elementor-widget elementor-widget-image\" data-id=\"664daed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a8583b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a8583b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f24de89\" data-id=\"f24de89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aec6c64 elementor-widget elementor-widget-spacer\" data-id=\"aec6c64\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48ccb22 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"48ccb22\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-de66d67\" data-wdt-settings=\"{&quot;id&quot;:&quot;de66d67&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"de66d67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff5658d start elementor-widget__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"ff5658d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-ff5658d\"><div class=\"wdt-heading-content-wrapper\">Dzi\u0119ki specyficznemu rozk\u0142adowi wielko\u015bci ziaren od 0 do 1 mm, MOSES\u00ae 0-1 jest idealnym zamiennikiem soli kamiennej lub soli \u015br\u00f3dziemnomorskiej. R\u00f3wnie\u017c pod wzgl\u0119dem czysto\u015bci i zr\u00f3wnowa\u017conego rozwoju, s\u00f3l ta przeniesie Ci\u0119 na inny poziom.\n\nMOSES\u00ae 0-1 jest szczeg\u00f3lnie odpowiedni do suchych zastosowa\u0144, takich jak produkcja przek\u0105sek (chrupek, ciastek itp.), mieszanek zi\u00f3\u0142 i przypraw, produkt\u00f3w mlecznych (mas\u0142a, sera itp.), produkt\u00f3w piekarniczych, produkt\u00f3w rybnych (w\u0119dzarni) itp.\nIdealny do wszystkich produkt\u00f3w spo\u017cywczych, do kt\u00f3rych wymagana jest s\u00f3l wysokiej jako\u015bci: ser\u00f3w, przetwor\u00f3w, produkt\u00f3w ciastkarskich, mi\u0119sa, ryb itp.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4c0432d animated-fast elementor-invisible\" data-id=\"4c0432d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ade5023 start wdt-cus-about1-iconbox wdt-cus-about1-iconbox-top elementor-widget__width-initial elementor-widget elementor-widget-wdt-icon-box\" data-id=\"ade5023\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#EDEDED&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#54595F&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;1&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-content-aside\" id=\"wdt-icon-box-ade5023\" data-settings=\"\"><div class=\"wdt-column-wrapper wdt-column-gap-custom \" data-column-settings=\"\" data-module-id=\"wdt-module-id-ade5023\" id=\"wdt-module-id-ade5023\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Najwy\u017csza jako\u015b\u0107 spo\u017cywcza (99,8% NaCl)<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Dos\u0142ownie ka\u017cde ziarenko jest sprawdzane pod k\u0105tem czysto\u015bci.\n\n\n<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Produkt naturalny<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">W komunikacji z klientami podkre\u015bl naturalne w\u0142a\u015bciwo\u015bci soli morskiej.\n\n\n<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Bogaty w minera\u0142y i pierwiastki \u015bladowe<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Podstawowe elementy cia\u0142a.\n\n\n<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>S\u00f3l bez numer\u00f3w E<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Idealny do linii produkcyjnych zar\u00f3wno konwencjonalnych, jak i ekologicznych.\n\n\n<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d44d872 e-flex e-con-boxed e-con e-parent\" data-id=\"d44d872\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac7d452 wdt-cus-our-policy wdt-cus-home2-iconbox center elementor-widget elementor-widget-wdt-icon-box\" data-id=\"ac7d452\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-icon-box-ac7d452\" data-id=\"ac7d452\" data-settings=\"\"><div class=\"wdt-icon-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:30,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:30,&quot;mobile&quot;:30,&quot;tablet&quot;:30}}\" id=\"wdt-icon-box-swiper-ac7d452\"><div class=\"wdt-icon-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Wielko\u015b\u0107 ziarna<\/h5><\/div><div class=\"wdt-content-description\">100-1180 mikrometr\u00f3w\n\n\n\n<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Rodzaje surowc\u00f3w<\/h5><\/div><div class=\"wdt-content-description\">S\u00f3l morska - S\u00f3l kamienna<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Opakowanie<\/h5><\/div><div class=\"wdt-content-description\">5KG - 10KG - 20KG - 25KG (WORKI)\n1000KG - 1250KG - 1500KG (JAMBO)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Dodatki<\/h5><\/div><div class=\"wdt-content-description\">Dost\u0119pne bez dodatk\u00f3w\n(Dost\u0119pne z jodanem potasu (jod)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Sk\u0142adowanie<\/h5><\/div><div class=\"wdt-content-description\">Przechowywa\u0107 w suchym miejscu.<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Wysy\u0142ka<\/h5><\/div><div class=\"wdt-content-description\">Ci\u0119\u017car\u00f3wka z przyczep\u0105<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-ac7d452\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1fb95a wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a1fb95a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_position&quot;:&quot;center left&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c098f57 animated-fast elementor-invisible\" data-id=\"c098f57\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56322e6 elementor-widget__width-initial center elementor-widget elementor-widget-wdt-heading\" data-id=\"56322e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-56322e6\"><div class=\"wdt-heading-content-wrapper\">Similar Items<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a336ad0 e-flex e-con-boxed e-con e-parent\" data-id=\"a336ad0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c19be22 wdt-cus-services-imgbox animated-fast elementor-widget__width-initial center elementor-invisible elementor-widget elementor-widget-wdt-image-box\" data-id=\"c19be22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;6&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;100&quot;,&quot;marquee_class&quot;:&quot;yes&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:13,&quot;sizes&quot;:[]},&quot;overflow_type&quot;:&quot;right&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_color&quot;:&quot;#6EC1E4&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_color&quot;:&quot;#FFC527&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-image-box-holder wdt-marquee-wrapper wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-image-box-c19be22\" data-id=\"c19be22\" data-settings=\"{&quot;enable_popup&quot;:&quot;&quot;,&quot;enable_hover_class&quot;:&quot;&quot;}\"><div class=\"wdt-image-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;right&quot;,&quot;overflow_opacity&quot;:null,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:13,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:6,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:13,&quot;mobile&quot;:13,&quot;tablet&quot;:13}}\" id=\"wdt-image-box-swiper-c19be22\"><div class=\"wdt-image-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-0-2-extra-fine-sea-salt\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png\" class=\"attachment-full size-full wp-image-17414\" alt=\"MOSES\u00ae 0.8-1, medium fine salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-0-2-extra-fine-sea-salt\/\">MOSES\u00ae 0-0,2, s\u00f3l ekstra drobna<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-2-0-8-fine-sea-salt\/\"rel=\"nofollow\" ><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png\" class=\"attachment-full size-full wp-image-17414\" alt=\"MOSES\u00ae 0.8-1, medium fine salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-2-0-8-fine-sea-salt\/\"rel=\"nofollow\" >MOSES\u00ae 0,2-0,8, s\u00f3l drobna<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-medium-fine-sea-salt\/\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.png\" class=\"attachment-full size-full wp-image-17416\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-medium-fine-sea-salt\/\">MOSES\u00ae 0,8-1, s\u00f3l \u015brednio-drobna<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-2-medium-fine-sea-salt\/\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2.png\" class=\"attachment-full size-full wp-image-17415\" alt=\"MOSES\u00ae 1-2, medium coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-2-medium-fine-sea-salt\/\">MOSES\u00ae 0,8-1,2, s\u00f3l \u015brednio-drobna<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-2-medium-coarse-sea-salt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2.png\" class=\"attachment-full size-full wp-image-17419\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-2-medium-coarse-sea-salt\/\">MOSES\u00ae 1-2, s\u00f3l \u015brednio gruba<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-3-medium-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3.png\" class=\"attachment-full size-full wp-image-17420\" alt=\"MOSES\u00ae 1-3, medium coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-3-medium-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 1-3, s\u00f3l \u015brednio gruba<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-4-coarse-sea-salt\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4.png\" class=\"attachment-full size-full wp-image-17421\" alt=\"MOSES\u00ae 1-4, coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-4-coarse-sea-salt\/\"rel=\"nofollow\" >MOSES\u00ae 1-4, s\u00f3l gruboziarnista<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-2-4-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png\" class=\"attachment-full size-full wp-image-17422\" alt=\"MOSES\u00ae 2-4, coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-2-4-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 2-4, s\u00f3l gruboziarnista<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-4-6-extra-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6.png\" class=\"attachment-full size-full wp-image-17423\" alt=\"MOSES\u00ae 4-6, extra coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-4-6-extra-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 4-6, s\u00f3l gruboziarnista<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-4-15-extra-coarse-sea-salt-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15.png\" class=\"attachment-full size-full wp-image-17424\" alt=\"MOSES\u00ae 4-15, extra coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-4-15-extra-coarse-sea-salt-2\/\">MOSES\u00ae 4-15, s\u00f3l gruboziarnista<\/a><\/h5><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-c19be22\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MOSES\u00ae 0-1, s\u00f3l drobna Dzi\u0119ki specyficznemu rozk\u0142adowi wielko\u015bci ziaren od 0 do 1 mm, MOSES\u00ae 0-1 jest idealnym zamiennikiem soli kamiennej lub soli \u015br\u00f3dziemnomorskiej. R\u00f3wnie\u017c pod wzgl\u0119dem czysto\u015bci i zr\u00f3wnowa\u017conego rozwoju, s\u00f3l ta przeniesie Ci\u0119 na inny poziom. MOSES\u00ae 0-1 jest szczeg\u00f3lnie odpowiedni do suchych zastosowa\u0144, takich jak produkcja przek\u0105sek (chrupek, ciastek itp.), mieszanek zi\u00f3\u0142 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38753,"parent":21786,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-21814","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/21814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/comments?post=21814"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/21814\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/21786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/media\/38753"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/media?parent=21814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}