{"id":21961,"date":"2024-12-29T14:28:12","date_gmt":"2024-12-29T12:28:12","guid":{"rendered":"https:\/\/uae.mosesexport.com\/moses-regular-tabletki-solne\/"},"modified":"2026-01-20T15:08:20","modified_gmt":"2026-01-20T13:08:20","slug":"moses-regular-tabletki-solne","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/pl\/sol\/sol-do-uzdatniania-wody\/sol-do-basenow\/moses-regular-tabletki-solne\/","title":{"rendered":"Tabletki solne"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21961\" class=\"elementor elementor-21961 elementor-17125\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19025cb wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"19025cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52e3998 animated-fast elementor-invisible\" data-id=\"52e3998\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06f86c9 start elementor-widget elementor-widget-wdt-heading\" data-id=\"06f86c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-06f86c9\"><div class=\"wdt-heading-content-wrapper\">MOSES\u00ae Tabletki solne<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09d05ab elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"09d05ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>MOSES\u00ae Tabletki solne to tabletki najwy\u017cszej jako\u015bci, przeznaczone do efektywnego zmi\u0119kczania wody, a jednocze\u015bnie odpowiednie do basen\u00f3w uzdatnianych za pomoc\u0105 system\u00f3w elektrolizy membranowej. Praktyczne, wydajne rozwi\u0105zanie do wielu zastosowa\u0144 w uzdatnianiu wody.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73c35ef wdt-cus-grid-img-counter\" data-wdt-settings=\"{&quot;id&quot;:&quot;73c35ef&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"73c35ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab116da elementor-widget elementor-widget-image\" data-id=\"ab116da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-1024x1024.webp\" class=\"attachment-large size-large wp-image-33584\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-1024x1024.webp 1024w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-1000x1000.webp 1000w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-100x100.webp 100w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-300x300.webp 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-150x150.webp 150w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-768x768.webp 768w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-1536x1536.webp 1536w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/MOSES\u00ae-REGULAR-Salt-Tablets-1-scaled-1-2048x2048.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-345c719 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"345c719\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2621f0\" data-id=\"e2621f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df61161 elementor-widget elementor-widget-spacer\" data-id=\"df61161\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ad032b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ad032b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5f8aee\" data-id=\"f5f8aee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7b3b9b2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7b3b9b2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-120e1d3\" data-wdt-settings=\"{&quot;id&quot;:&quot;120e1d3&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"120e1d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa58cd8 start elementor-widget elementor-widget-wdt-heading\" data-id=\"aa58cd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-aa58cd8\"><div class=\"wdt-heading-content-wrapper\">Tabletki solne nadaj\u0105 si\u0119 do zmi\u0119kczania wody pitnej i wody wykorzystywanej w produkcji \u017cywno\u015bci. Zaprojektowano je z my\u015bl\u0105 o niezawodnym stosowaniu w domowych i przemys\u0142owych systemach zmi\u0119kczania wody.\n\nPonadto, s\u00f3l mo\u017ce by\u0107 stosowana jako s\u00f3l basenowa do basen\u00f3w uzdatnianych metod\u0105 elektrolizy membranowej i elektrochlorowania.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a833aa2 animated-fast elementor-invisible\" data-id=\"a833aa2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02e3e40 start wdt-cus-about1-iconbox wdt-cus-about1-iconbox-top elementor-widget__width-initial elementor-widget elementor-widget-wdt-icon-box\" data-id=\"02e3e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#EDEDED&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#54595F&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;1&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-content-aside\" id=\"wdt-icon-box-02e3e40\" data-settings=\"\"><div class=\"wdt-column-wrapper wdt-column-gap-custom \" data-column-settings=\"\" data-module-id=\"wdt-module-id-02e3e40\" id=\"wdt-module-id-02e3e40\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Nie zawiera \u017cadnych dodatk\u00f3w<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Bez zabawy z chemikaliami. Tylko czysta s\u00f3l.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Bez zbrylania<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Kszta\u0142t zbiornika sprzyja regularnej produkcji solanki.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Do zmi\u0119kczania wody oraz elektrolizy membranowej<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">2-in-1\n\n\n<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Przekroczy\u0142o najsurowsze standardy<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">S\u00f3l zmi\u0119kczaj\u0105ca o jako\u015bci spo\u017cywczej.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6331f82 e-flex e-con-boxed e-con e-parent\" data-id=\"6331f82\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-360e3c4 wdt-cus-our-policy wdt-cus-home2-iconbox center elementor-widget elementor-widget-wdt-icon-box\" data-id=\"360e3c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_color&quot;:&quot;#6EC1E4&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_color&quot;:&quot;#003057&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-icon-box-360e3c4\" data-id=\"360e3c4\" data-settings=\"\"><div class=\"wdt-icon-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:30,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:30,&quot;mobile&quot;:30,&quot;tablet&quot;:30}}\" id=\"wdt-icon-box-swiper-360e3c4\"><div class=\"wdt-icon-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Wielko\u015b\u0107 ziarna<\/h5><\/div><div class=\"wdt-content-description\">\u00f8 25 mm x 12 mm\n\n<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Rodzaje surowc\u00f3w<\/h5><\/div><div class=\"wdt-content-description\">S\u00f3l morska - S\u00f3l kamienna<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Opakowanie<\/h5><\/div><div class=\"wdt-content-description\">20 KG - 25 KG (WORKI)\n1000 KG - 1250 KG - 1500 KG (JAMBO)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Dodatki<\/h5><\/div><div class=\"wdt-content-description\">Dost\u0119pne bez dodatk\u00f3w<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Sk\u0142adowanie<\/h5><\/div><div class=\"wdt-content-description\">Przechowywa\u0107 w suchym miejscu<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Wysy\u0142ka<\/h5><\/div><div class=\"wdt-content-description\">Ci\u0119\u017car\u00f3wka z przyczep\u0105<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-360e3c4\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca373f3 elementor-widget elementor-widget-spacer\" data-id=\"ca373f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c2d5f0 e-flex e-con-boxed e-con e-parent\" data-id=\"6c2d5f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b72821f elementor-widget elementor-widget-text-editor\" data-id=\"b72821f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"quote-section\">\n  <h3>Request a Quote<\/h3>\n  <div class=\"packaging-selector\">\n    <label for=\"product-packaging\">Select Packaging:<\/label>\n    <select id=\"product-packaging\">\n      <option value=\"\">Choose packaging<\/option>\n      <option>5 KG BAG<\/option>\n      <option>10 KG BAG<\/option>\n      <option>20 KG BAG<\/option>\n      <option>25 KG BAG<\/option>\n      <option>1000 KG JUMBO<\/option>\n      <option>1250 KG JUMBO<\/option>\n      <option>1500 KG JUMBO<\/option>\n    <\/select>\n  <\/div>\n  <button id=\"get-quote-btn\" class=\"quote-button\">Get Quote<\/button>\n<\/div>\n\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", () => {\n  const quoteBtn = document.getElementById(\"get-quote-btn\");\n  const packagingSelect = document.getElementById(\"product-packaging\");\n\n  quoteBtn.addEventListener(\"click\", () => {\n    const packaging = packagingSelect.value.trim();\n   \/\/ if (!packaging) {\n    \/\/  alert(\"Please select a packaging option first.\");\n \/\/    return;\n  \/\/  }\n\n    \/\/ Get the full title tag content and extract only the part before |\n    const pageTitle = document.title.trim();\n    const saltType = pageTitle.split('|')[0].trim();\n\n    \/\/ Detect product category based on the salt type\n    const productCategory = detectProductCategoryFromSaltType(saltType);\n\n    \/\/ Encode everything as Base64 to avoid URL encoding issues\n    const saltTypeBase64 = btoa(unescape(encodeURIComponent(saltType)));\n    const productCategoryBase64 = btoa(unescape(encodeURIComponent(productCategory)));\n    const packagingBase64 = btoa(unescape(encodeURIComponent(packaging)));\n\n    const params = new URLSearchParams({\n      packaging_b64: packagingBase64,\n      'product-category_b64': productCategoryBase64,\n      salttype_b64: saltTypeBase64\n    });\n\n    console.log('Redirecting with params:', {\n      packaging: packaging,\n      productCategory: productCategory,\n      saltType: saltType\n    });\n\n    \/\/ Redirect safely to request quote page\n    window.location.href = `\/price-enquiry\/?${params.toString()}`;\n  });\n\n  function detectProductCategoryFromSaltType(saltType) {\n    const productCategoryMap = [\n      [\/MOSES\u00ae REGULAR, salt tablets|MOSES\u00ae CRYSTALS, salt crystals\/i, \"Salt For Water Softening\"],\n      [\/MOSES\u00ae GRANULAR, Salt\/i, \"Dishwasher Salt\"],\n      [\/MOSES\u00ae REGULAR, Salt Tablets|MOSES\u00ae Swimming Pool Salt\/i, \"Swimming Pool Salt\"],\n      [\/MOSES\u00ae1-3, salt for animal feed and for agriculture|MOSES\u00ae 2-4, salt for agriculture\/i, \"Agricultural salt\"],\n      [\/MOSES\u00ae Fine Salt|MOSES\u00ae Coarse Salt|MOSES\u00ae fleur de sel\/i, \"Sea Salt! For The Food Service Sector\"],\n      [\/Moses\u00ae 0-1 Fine Road Salt|MOSES\u00ae 1-4, Coarse Road Salt|MOSES ROAD SALT\u00ae de-icing salt\/i, \"Road Salt\"],\n      [\/Moses\u00ae 0-1, fine salt|MOSES\u00ae 1-3, medium coarse salt|MOSES\u00ae 2-4, coarse salt|MOSES\u00ae 4-6, extra coarse salt|MOSES\u00ae 4-15, extra coarse salt|MOSES 6-15, extra coarse technical salt\/i, \"Industrial Salt\"],\n      [\/MOSES\u00ae 0-0.2, extra fine sea salt|MOSES\u00ae 0.2-0.8, fine sea salt|MOSES\u00ae 0-1, fine sea salt|MOSES\u00ae 0.8-1, medium fine sea salt|MOSES\u00ae 0.8-1.2, medium fine sea salt|MOSES\u00ae 1-2, medium coarse sea salt|MOSES\u00ae 1-3, medium coarse sea salt|MOSES\u00ae 1-4, coarse sea salt|MOSES\u00ae 2-4, coarse sea salt|MOSES\u00ae 4-6, extra coarse sea salt|MOSES\u00ae 4-15, extra coarse sea salt\/i, \"Salt To Taste\"],\n      [\/MOSES1-3, salt for animal feed and for agriculture|MOSES,Salt Block\/i, \"Salt for animal feed\"]\n    ];\n    \n    for (const [regex, productCategory] of productCategoryMap) {\n      if (regex.test(saltType)) {\n        console.log('Detected product category:', productCategory, 'for salt type:', saltType);\n        return productCategory;\n      }\n    }\n    \n    \/\/ Default fallback if no match found\n    console.log('No product category match found, using default: Select Product category');\n    return \"Select Product category\";\n  }\n});\n<\/script>\n\n<style>\n.quote-section {\n  background: #f9f9f9;\n  padding: 20px;\n  margin: 20px 0;\n  border-radius: 8px;\n  border: 1px solid #ddd;\n}\n.packaging-selector label {\n  font-weight: 600;\n  margin-bottom: 5px;\n  display: block;\n}\n.packaging-selector select, .quote-button {\n  padding: 10px;\n  border-radius: 4px;\n  border: 1px solid #ccc;\n  font-size: 15px;\n}\n.quote-button {\n  background: #007cba;\n  color: #fff;\n  border: none;\n  cursor: pointer;\n  font-weight: bold;\n  margin-top: 10px;\n}\n.quote-button:hover {\n  background: #005a87;\n}\n<\/style><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f10cdc e-flex e-con-boxed e-con e-parent\" data-id=\"7f10cdc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c983173 wdt-cus-accordion1 elementor-widget elementor-widget-wdt-accordion-and-toggle\" data-id=\"c983173\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-accordion-and-toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-accordion-toggle-holder wdt-module-toggle wdt-template-classic wdt-expand-collapse-position-end\" id=\"wdt-accordion-and-toggle-c983173\"><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\"><div class=\"wdt-accordion-toggle-title-prefix number\">1<\/div>Jakiego rodzaju soli powinienem u\u017cywa\u0107 do basenu z wod\u0105 s\u0142on\u0105?<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">W basenie z generatorem chloru solnego nale\u017cy u\u017cywa\u0107 soli kopalnianej. U\u017cywaj soli o czysto\u015bci 95% lub wy\u017cszej, poniewa\u017c wy\u017csza czysto\u015b\u0107 znacznie zmniejsza ryzyko zabrudzenia basenu lub uszkodzenia sprz\u0119tu. Aby przed\u0142u\u017cy\u0107 \u017cywotno\u015b\u0107 ogniwa solnego, czy\u015b\u0107 je tylko wtedy, gdy jest to konieczne.  <\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa3dc91 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"fa3dc91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_position&quot;:&quot;center left&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d3194d animated-fast elementor-invisible\" data-id=\"2d3194d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cce0ff elementor-widget__width-initial elementor-widget-tablet__width-initial center elementor-widget elementor-widget-wdt-heading\" data-id=\"2cce0ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-2cce0ff\"><div class=\"wdt-heading-content-wrapper\">Podobny produkt<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3b99c33 e-flex e-con-boxed e-con e-parent\" data-id=\"3b99c33\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d4e0b3 wdt-cus-services-imgbox animated-fast elementor-widget__width-initial center elementor-invisible elementor-widget elementor-widget-wdt-image-box\" data-id=\"1d4e0b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;100&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-image-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-custom-template\" id=\"wdt-image-box-1d4e0b3\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/sol-do-basenow-moses\/\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/\u0645\u0644\u062d-\u062d\u0645\u0627\u0645-\u0627\u0644\u0633\u0628\u0627\u062d\u0629.png\" class=\"attachment-full size-full wp-image-35200\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/\u0645\u0644\u062d-\u062d\u0645\u0627\u0645-\u0627\u0644\u0633\u0628\u0627\u062d\u0629.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/\u0645\u0644\u062d-\u062d\u0645\u0627\u0645-\u0627\u0644\u0633\u0628\u0627\u062d\u0629-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/\u0645\u0644\u062d-\u062d\u0645\u0627\u0645-\u0627\u0644\u0633\u0628\u0627\u062d\u0629-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/\u0645\u0644\u062d-\u062d\u0645\u0627\u0645-\u0627\u0644\u0633\u0628\u0627\u062d\u0629-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/pl\/sol-do-basenow-moses\/\">MOSES\u00ae S\u00f3l do basen\u00f3w<\/a><\/h5><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MOSES\u00ae REGULAR, Tabletki solne Tabletki solne MOSES\u00ae REGULAR to wysokiej jako\u015bci tabletki solne, kt\u00f3re mo\u017cna stosowa\u0107 jako s\u00f3l zmi\u0119kczaj\u0105c\u0105 wod\u0119, ale tak\u017ce jako s\u00f3l do basen\u00f3w czyszczonych metod\u0105 elektrolizy membranowej. Unikalna i praktyczna formu\u0142a! Nie zawiera \u017cadnych dodatk\u00f3w \u017badnej zabawy z chemikaliami. Tylko czysta s\u00f3l. Bez zbrylania Kszta\u0142t zbiornika sprzyja regularnej produkcji solanki. Do zmi\u0119kczania [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33516,"parent":22016,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-21961","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/21961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/comments?post=21961"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/21961\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/22016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/media\/33516"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/media?parent=21961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}