{"id":22081,"date":"2024-12-22T13:56:58","date_gmt":"2024-12-22T11:56:58","guid":{"rendered":"https:\/\/uae.mosesexport.com\/sol-przemyslowa\/"},"modified":"2026-02-03T15:05:27","modified_gmt":"2026-02-03T13:05:27","slug":"sol-przemyslowa","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/pl\/sol\/sol-przemyslowa\/","title":{"rendered":"S\u00f3l przemys\u0142owa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22081\" class=\"elementor elementor-22081 elementor-16596\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d0bfa3 e-flex e-con-boxed e-con e-parent\" data-id=\"3d0bfa3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a046ce6 elementor-widget elementor-widget-heading\" data-id=\"a046ce6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/sol-przemyslowa\/\">S\u00f3l przemys\u0142owa<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe0a83d elementor-widget elementor-widget-text-editor\" data-id=\"fe0a83d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>W MOSES SALT przetwarzamy surow\u0105 s\u00f3l pozyskiwan\u0105 z r\u00f3\u017cnych basen\u00f3w solnych Morza \u015ar\u00f3dziemnego, stosuj\u0105c wy\u0142\u0105cznie naturalne metody, tj. sita i magnesy na wszystkich etapach produkcji, bez dodatku chemikali\u00f3w. Ponadto, standaryzujemy j\u0105, stosuj\u0105c mniejszy zakres \u015brednicy ziaren, co przek\u0142ada si\u0119 na szerszy zakres rozmiar\u00f3w ziaren, dzi\u0119ki czemu mo\u017cesz wybra\u0107 t\u0119, kt\u00f3ra najlepiej odpowiada Twoim potrzebom.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6da8083 wdt-no-full-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6da8083\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fe6f522 animated-fast elementor-invisible\" data-id=\"fe6f522\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7332c3c start elementor-widget elementor-widget-wdt-heading\" data-id=\"7332c3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_background_background&quot;:&quot;classic&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-7332c3c\"><div class=\"wdt-heading-content-wrapper\">S\u00f3l przemys\u0142owa jest niezb\u0119dnym materia\u0142em w zastosowaniach przemys\u0142owych. Nasza s\u00f3l kamienna to produkt naturalny, wydobywany z naszych w\u0142asnych z\u0142\u00f3\u017c soli w Egipcie, kt\u00f3re powsta\u0142y z prastarego morza licz\u0105cego oko\u0142o 250 milion\u00f3w lat.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ef20b4 wdt-cus-grid-img-counter\" data-wdt-settings=\"{&quot;id&quot;:&quot;2ef20b4&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"2ef20b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0aa97e5 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"0aa97e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/BACKGROUND.png\" class=\"attachment-full size-full wp-image-21498\" alt=\"s\u00f3l przemys\u0142owa\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/BACKGROUND.png 900w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/BACKGROUND-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/BACKGROUND-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/BACKGROUND-768x576.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b41ca4e e-flex e-con-boxed e-con e-parent\" data-id=\"b41ca4e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eea42df elementor-widget elementor-widget-heading\" data-id=\"eea42df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">producenci soli<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3167f27 elementor-widget elementor-widget-text-editor\" data-id=\"3167f27\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gruboziarnist\u0105 s\u00f3l morsk\u0105 p\u0142uczemy w \u015bwie\u017cej wodzie i rozdrabniamy na r\u00f3\u017cne wielko\u015bci ziaren \u2013 od bardzo drobnego do supergrubego. Sprawdzamy ka\u017cde ziarenko pod k\u0105tem zanieczyszcze\u0144 i stale monitorujemy jako\u015b\u0107 naszego produktu ko\u0144cowego: wysokiej jako\u015bci s\u00f3l morsk\u0105, gotow\u0105 do u\u017cycia na wszystkich liniach produkcyjnych.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-353becc e-flex e-con-boxed e-con e-parent\" data-id=\"353becc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f2ae5c start start elementor-widget-mobile__width-inherit wdt-cus-service-style-01 elementor-widget elementor-widget-wdt-image-box\" data-id=\"1f2ae5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_normal_background_background&quot;:&quot;classic&quot;,&quot;button_normal_background_color&quot;:&quot;#FFC52700&quot;,&quot;button_hover_background_background&quot;:&quot;classic&quot;,&quot;button_hover_background_color&quot;:&quot;#FFC52700&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;item_normal_background_background&quot;:&quot;gradient&quot;,&quot;item_normal_background_color&quot;:&quot;#003057&quot;,&quot;item_hover_background_background&quot;:&quot;gradient&quot;,&quot;_animation&quot;:&quot;none&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-image-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-custom-template\" id=\"wdt-image-box-1f2ae5c\" data-settings=\"{&quot;enable_popup&quot;:&quot;&quot;,&quot;enable_hover_class&quot;:&quot;&quot;}\"><div class=\"wdt-column-wrapper wdt-column-gap-wide \" data-column-settings=\"\" data-module-id=\"wdt-module-id-1f2ae5c\" id=\"wdt-module-id-1f2ae5c\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-0-1-drobna-sol-morska-2\/\"><img decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/a2ec6995cd284aeb7318468f7dbc1eb24788a3bd_Korrel_MARSEL_SALCO_0_1_1440x952px.png\" class=\"attachment-full size-full wp-image-16625\" alt=\"MOSES\u00ae 0-1, fine Coarse sea salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/a2ec6995cd284aeb7318468f7dbc1eb24788a3bd_Korrel_MARSEL_SALCO_0_1_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/a2ec6995cd284aeb7318468f7dbc1eb24788a3bd_Korrel_MARSEL_SALCO_0_1_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-0-1-drobna-sol-morska-2\/\"><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-0-1-drobna-sol-morska-2\/\">MOSES 0-1, s\u00f3l drobna<\/a><\/h5><\/div><div class=\"wdt-content-description\">Nadaje si\u0119 do r\u00f3\u017cnych zastosowa\u0144 na sucho, wielko\u015b\u0107 ziarna od 0 do 1 mm<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-1-3-srednio-gruboziarnista-sol-morska-2\/\"><img decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/f1663efdfb1064d7a7346f0c68dd4d0b3237f637_Korrel_MARSEL_SALCO_VAATWASZOUT_1_3_1440x952px.png\" class=\"attachment-full size-full wp-image-16624\" alt=\"MOSES\u00ae 1-3, medium coarse sea salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/f1663efdfb1064d7a7346f0c68dd4d0b3237f637_Korrel_MARSEL_SALCO_VAATWASZOUT_1_3_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/f1663efdfb1064d7a7346f0c68dd4d0b3237f637_Korrel_MARSEL_SALCO_VAATWASZOUT_1_3_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-1-3-srednio-gruboziarnista-sol-morska-2\/\"><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-1-3-srednio-gruboziarnista-sol-morska-2\/\">MOSES 1-3, s\u00f3l \u015brednio gruba<\/a><\/h5><\/div><div class=\"wdt-content-description\">s\u00f3l o twardym i czystym uziarnieniu ma wielko\u015b\u0107 od 1 do 3 mm<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-2-4-gruboziarnista-sol-morska-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px.png\" class=\"attachment-full size-full wp-image-16628\" alt=\"Technical salt whose grain size ranges between 2 and 4 mm\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/d63eadae9f475324fc1e6510cb83aef2967549a3_Korrel_MARSEL_SALCO_VAATWASZOUT_2_4_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-2-4-gruboziarnista-sol-morska-2\/\"><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-2-4-gruboziarnista-sol-morska-2\/\">MOSES 2-4, gruba s\u00f3l<\/a><\/h5><\/div><div class=\"wdt-content-description\">S\u00f3l techniczna o wielko\u015bci ziaren od 2 do 4 mm<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-4-6-bardzo-gruboziarnista-sol-morska-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/4-6.png\" class=\"attachment-full size-full wp-image-16769\" alt=\"Technical salt whose grain size ranges between 4 and 6 mm\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/4-6.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/4-6-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/4-6-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/4-6-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-4-6-bardzo-gruboziarnista-sol-morska-2\/\"><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-4-6-bardzo-gruboziarnista-sol-morska-2\/\">MOSES 4-6, s\u00f3l gruboziarnista<\/a><\/h5><\/div><div class=\"wdt-content-description\">S\u00f3l techniczna o wielko\u015bci ziaren od 4 do 6 mm<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-4-15-bardzo-gruboziarnista-sol-morska-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/aaafb1d6a58d37e1e96890dcc17c9e63707177d5_Korrel_MARSEL_SS_CRYSTALS_5_15_1440x952px.png\" class=\"attachment-full size-full wp-image-16626\" alt=\"MOSES\u00ae 4-15, extra coarse sea salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/aaafb1d6a58d37e1e96890dcc17c9e63707177d5_Korrel_MARSEL_SS_CRYSTALS_5_15_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/aaafb1d6a58d37e1e96890dcc17c9e63707177d5_Korrel_MARSEL_SS_CRYSTALS_5_15_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-4-15-bardzo-gruboziarnista-sol-morska-2\/\"><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-4-15-bardzo-gruboziarnista-sol-morska-2\/\">MOSES 4-15, s\u00f3l gruboziarnista<\/a><\/h5><\/div><div class=\"wdt-content-description\">S\u00f3l techniczna o wielko\u015bci ziaren od 4 do 15 mm<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-6-15-bardzo-gruboziarnista-sol-techniczna\/\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"340\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/f5c203e90310baa988191b2713ffa14dea5ecfe5_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px.png\" class=\"attachment-full size-full wp-image-16623\" alt=\"MOSES 6-15, extra coarse technical salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/f5c203e90310baa988191b2713ffa14dea5ecfe5_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px.png 450w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/f5c203e90310baa988191b2713ffa14dea5ecfe5_Korrel_MARSEL_SS_CRYSTALS_SALCO_5_15_1440x952px-300x227.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-6-15-bardzo-gruboziarnista-sol-techniczna\/\"><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/pl\/moses-6-15-bardzo-gruboziarnista-sol-techniczna\/\">MOSES 6-15, s\u00f3l techniczna gruboziarnista<\/a><\/h5><\/div><div class=\"wdt-content-description\">S\u00f3l techniczna o granulacji od 6 do 15 mm<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26267a2 e-flex e-con-boxed e-con e-parent\" data-id=\"26267a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fce187f elementor-widget__width-initial center elementor-widget elementor-widget-wdt-heading\" data-id=\"fce187f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-fce187f\"><h4 class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Obszary zastosowa\u0144<\/span><\/h4><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-997ffff elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"997ffff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77e334e\" data-id=\"77e334e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dce9ca6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dce9ca6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-72b9c1b\" data-wdt-settings=\"{&quot;id&quot;:&quot;72b9c1b&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"72b9c1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f411c0b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-inherit center elementor-widget elementor-widget-wdt-heading\" data-id=\"f411c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-f411c0b\"><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Przemys\u0142 chemiczny<\/span><\/p><div class=\"wdt-heading-content-wrapper\">Sole potasu odgrywaj\u0105 wa\u017cn\u0105 rol\u0119 w procesach metalurgicznych. Chlorki potasu s\u0105 stosowane do obr\u00f3bki powierzchni i cynkowania, jako sole hartownicze i lutownicze oraz jako sole wytopowe w chemii odlewniczej. Przemys\u0142owe sole kamienne s\u0105 niezb\u0119dnym materia\u0142em w przemy\u015ble przetw\u00f3rstwa metali.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0880971 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"0880971\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Chemical-industry-768x432.png\" class=\"attachment-medium_large size-medium_large wp-image-36008\" alt=\"Przemys\u0142 chemiczny\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Chemical-industry-768x432.png 768w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Chemical-industry-600x338.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Chemical-industry-300x169.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Chemical-industry.png 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ca511c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4ca511c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d582bc7\" data-id=\"d582bc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e31d38f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e31d38f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-32390c0\" data-wdt-settings=\"{&quot;id&quot;:&quot;32390c0&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"32390c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-590fef1 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-inherit center elementor-widget elementor-widget-wdt-heading\" data-id=\"590fef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-590fef1\"><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Bran\u017ca d\u00f3br konsumpcyjnych<\/span><\/p><div class=\"wdt-heading-content-wrapper\">W przemy\u015ble tekstylnym s\u00f3l przemys\u0142owa jest stosowana jako wzmacniacz barwnik\u00f3w w procesie przetwarzania i rafinacji tkanin. Dodana do k\u0105pieli barwi\u0105cej s\u00f3l zapewnia pe\u0142ne wnikni\u0119cie koloru w tkanin\u0119. Katalityczne dzia\u0142anie bezwodnego siarczanu magnezu jest niezb\u0119dne do produkcji materia\u0142\u00f3w tekstylnych nie\u017celaznych.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-118c2ef elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"118c2ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Consumer-goods-industry-768x432.png\" class=\"attachment-medium_large size-medium_large wp-image-36009\" alt=\"Bran\u017ca d\u00f3br konsumpcyjnych\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Consumer-goods-industry-768x432.png 768w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Consumer-goods-industry-600x338.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Consumer-goods-industry-300x169.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Consumer-goods-industry.png 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b3851a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2b3851a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d7897f\" data-id=\"3d7897f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-39ffe65 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"39ffe65\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-82857b0\" data-wdt-settings=\"{&quot;id&quot;:&quot;82857b0&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"82857b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ee17fc elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-inherit center elementor-widget elementor-widget-wdt-heading\" data-id=\"5ee17fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-5ee17fc\"><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Dalsze procesy (siarczan potasu)<\/span><\/p><div class=\"wdt-heading-content-wrapper\">Siarczan potasu s\u0142u\u017cy jako materia\u0142 bazowy w r\u00f3\u017cnych procesach przemys\u0142owych i komercyjnych. Innymi przyk\u0142adami s\u0105 roztwory p\u0142ucz\u0105ce z borem w przemy\u015ble naftowym i gazowym, produkcja farb i pigment\u00f3w oraz produkcja dwutlenku tytanu.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5384a5 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"f5384a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Industrial-applications-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-36010\" alt=\"Zastosowania przemys\u0142owe\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Industrial-applications-768x432.jpg 768w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Industrial-applications-600x338.jpg 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Industrial-applications-300x169.jpg 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2026\/01\/Industrial-applications.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>S\u00f3l przemys\u0142owa W firmie MOSES SALT przetwarzamy surow\u0105 s\u00f3l pozyskiwan\u0105 z r\u00f3\u017cnych basen\u00f3w solnych Morza \u015ar\u00f3dziemnego, stosuj\u0105c wy\u0142\u0105cznie naturalne metody, tj. sita i magnesy na wszystkich etapach produkcji, bez dodatku chemikali\u00f3w. Ponadto standaryzujemy j\u0105, stosuj\u0105c mniejszy zakres \u015brednicy ziarna, co przek\u0142ada si\u0119 na szerszy zakres rozmiar\u00f3w ziarna, dzi\u0119ki czemu mo\u017cesz wybra\u0107 t\u0119, kt\u00f3ra najlepiej odpowiada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21498,"parent":22105,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22081","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/22081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/comments?post=22081"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/22081\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/pages\/22105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/media\/21498"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/pl\/wp-json\/wp\/v2\/media?parent=22081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}