{"id":26885,"date":"2024-04-10T04:07:27","date_gmt":"2024-04-10T02:07:27","guid":{"rendered":"https:\/\/uae.mosesexport.com\/casa-principal\/"},"modified":"2025-10-06T13:29:29","modified_gmt":"2025-10-06T10:29:29","slug":"casa-principal","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/pt-pt\/","title":{"rendered":"Casa Principal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26885\" class=\"elementor elementor-26885 elementor-11820\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8027c9b elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle wdt-dark-bg wdt-header-with-section animated-fast elementor-section-full_width elementor-section-height-default elementor-invisible\" data-id=\"8027c9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;100&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:16128,&quot;url&quot;:&quot;https:\\\/\\\/uae.mosesexport.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/937-Salt-at-your-service_V81.png&quot;}],&quot;background_slideshow_slide_transition&quot;:&quot;slide_right&quot;,&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-89c6fb5\" data-id=\"89c6fb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ea7cb6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4ea7cb6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-66921ca\" data-id=\"66921ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e25fa7b start elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wdt-heading\" data-id=\"e25fa7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-e25fa7b\"><div class=\"wdt-heading-subtitle-wrapper wdt-heading-align-1 \"><span class=\"wdt-heading-subtitle\">Vamos trabalhar<\/span><\/div><h2 class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Exporta\u00e7\u00e3o de sal eg\u00edpcio de alta qualidade<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78c84b3 start elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wdt-heading\" data-id=\"78c84b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-78c84b3\"><div class=\"wdt-heading-content-wrapper\">Uma empresa eg\u00edpcia para o fabrico e produ\u00e7\u00e3o dos melhores tipos de sal de todos os tipos<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-382cdbf elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"382cdbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2163582 elementor-widget__width-auto center elementor-widget elementor-widget-wdt-button\" data-id=\"2163582\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;item_normal_background_color&quot;:&quot;#54595F&quot;,&quot;item_hover_background_color&quot;:&quot;#FFC527&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-link wdt-button-style-default wdt-button-size-nm wdt-animation- wdt-button-icon-after\" id=\"wdt-button-2163582\"><a class=\"wdt-button\" href=\"https:\/\/uae.mosesexport.com\/contact\/\"><div class=\"wdt-button-text\"><span>Contate-nos<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd9129a elementor-widget__width-auto center elementor-widget elementor-widget-wdt-button\" data-id=\"fd9129a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-link wdt-button-style-default wdt-button-size-nm wdt-animation- wdt-button-icon-after\" id=\"wdt-button-fd9129a\"><a class=\"wdt-button\" href=\"https:\/\/uae.mosesexport.com\/about\/\"><div class=\"wdt-button-text\"><span>Sobre n\u00f3s<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc4a46 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fbc4a46\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b0093bc elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"b0093bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-7dc621e e-flex e-con-boxed e-con e-parent\" data-id=\"7dc621e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adda05c elementor-widget elementor-widget-heading\" data-id=\"adda05c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A solu\u00e7\u00e3o certa adaptada ao seu mercado.\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-885b4cd e-flex e-con-boxed e-con e-parent\" data-id=\"885b4cd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3c10f4 start start elementor-widget-mobile__width-inherit wdt-cus-service-style-01 elementor-widget elementor-widget-wdt-image-box\" data-id=\"d3c10f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:40,&quot;sizes&quot;:[]},&quot;button_normal_background_background&quot;:&quot;classic&quot;,&quot;button_normal_background_color&quot;:&quot;#FFC52700&quot;,&quot;button_hover_background_background&quot;:&quot;classic&quot;,&quot;button_hover_background_color&quot;:&quot;#FFC52700&quot;,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;mouse_wheel_scroll&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;item_normal_background_background&quot;:&quot;gradient&quot;,&quot;item_normal_background_color&quot;:&quot;#003057&quot;,&quot;item_hover_background_background&quot;:&quot;gradient&quot;,&quot;_animation&quot;:&quot;none&quot;,&quot;effect&quot;:&quot;coverflow&quot;,&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;carousel_arrows_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_arrows_default_normal_background_color&quot;:&quot;#003057&quot;,&quot;carousel_arrows_default_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_arrows_default_hover_background_color&quot;:&quot;#003057&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_color&quot;:&quot;#003057&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_color&quot;:&quot;#FFC527&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:300,&quot;autoplay_speed&quot;:5000,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-image-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-image-box-d3c10f4\" data-id=\"d3c10f4\" data-settings=\"{&quot;enable_popup&quot;:&quot;&quot;,&quot;enable_hover_class&quot;:&quot;&quot;}\"><div class=\"wdt-image-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;coverflow&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;yes&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;autoplay_direction&quot;:&quot;&quot;,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:40,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:40,&quot;mobile&quot;:20,&quot;tablet&quot;:20}}\" id=\"wdt-image-box-swiper-d3c10f4\"><div class=\"wdt-image-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/salt-for-water-treatment\/\"rel=\"nofollow\" ><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635.png\" class=\"attachment-full size-full wp-image-15943\" alt=\"MOSES\u00ae REGULAR, Salt Tablets\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/salt-for-water-treatment\/\"rel=\"nofollow\" ><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/salt-for-water-treatment\/\"rel=\"nofollow\" >Sal para tratamento de \u00e1guas<\/a><\/h5><\/div><div class=\"wdt-content-description\">Sal natural especialmente fabricado para o tratamento de \u00e1guas<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/industrial-salt\/\"rel=\"nofollow\" ><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0635\u0646\u0627\u0639\u064a.png\" class=\"attachment-full size-full wp-image-15945\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0635\u0646\u0627\u0639\u064a.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0635\u0646\u0627\u0639\u064a-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0635\u0646\u0627\u0639\u064a-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0635\u0646\u0627\u0639\u064a-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/industrial-salt\/\"rel=\"nofollow\" ><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/industrial-salt\/\"rel=\"nofollow\" >Sal Industrial<\/a><\/h5><\/div><div class=\"wdt-content-description\">Sal Industrial para Venda \u2013 Alta Qualidade e Vers\u00e1til para Uso Industrial<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/road-salt\/\" target=\"_blank\" rel=\"nofollow\" ><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0637\u0631\u064a\u0642.png\" class=\"attachment-full size-full wp-image-15944\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0637\u0631\u064a\u0642.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0637\u0631\u064a\u0642-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0637\u0631\u064a\u0642-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0637\u0631\u064a\u0642-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/road-salt\/\" target=\"_blank\" rel=\"nofollow\" ><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/road-salt\/\" target=\"_blank\" rel=\"nofollow\" >Sal de estrada<\/a><\/h5><\/div><div class=\"wdt-content-description\">Sal de estrada seguro com um tamanho de gr\u00e3o at\u00e9 5 mm<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/table-salt\/\"rel=\"nofollow\" ><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635.png\" class=\"attachment-full size-full wp-image-15943\" alt=\"MOSES\u00ae REGULAR, Salt Tablets\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/table-salt\/\"rel=\"nofollow\" ><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/table-salt\/\"rel=\"nofollow\" >O Setor dos Servi\u00e7os Alimentares<\/a><\/h5><\/div><div class=\"wdt-content-description\">Sal marinho eg\u00edpcio fabricado para sal de cozinha \u2013 alta qualidade, pureza e efici\u00eancia<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/salt-to-taste\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0645\u0644\u062d-\u0628\u062d\u0631.png\" class=\"attachment-full size-full wp-image-16308\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0645\u0644\u062d-\u0628\u062d\u0631.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0645\u0644\u062d-\u0628\u062d\u0631-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0645\u0644\u062d-\u0628\u062d\u0631-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0645\u0644\u062d-\u0628\u062d\u0631-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/salt-to-taste\/\"rel=\"nofollow\" ><div class=\"wdt-button-text\"><span>View<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/salt-to-taste\/\"rel=\"nofollow\" >Sal a gosto<\/a><\/h5><\/div><div class=\"wdt-content-description\">Sal marinho eg\u00edpcio em bruto \u00e0 venda agora - puro, natural e vers\u00e1til. A sua escolha<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/agricultural-salt\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png\" class=\"attachment-full size-full wp-image-17422\" alt=\"MOSES\u00ae 2-4, coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/agricultural-salt\/\"rel=\"nofollow\" ><div class=\"wdt-button-text\"><span>view<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/agricultural-salt\/\"rel=\"nofollow\" >Sal agr\u00edcola<\/a><\/h5><\/div><div class=\"wdt-content-description\">Sal-gema eg\u00edpcio em bruto para venda \u2013 Sal para sal agr\u00edcola<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group wdt-media-image-cover\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/salt-for-animal-feed\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/\u0642\u0627\u0644\u0628-\u062d\u064a\u0648\u0627\u0646\u064a.png\" class=\"attachment-full size-full wp-image-17564\" alt=\"MOSES, Salt Block\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/\u0642\u0627\u0644\u0628-\u062d\u064a\u0648\u0627\u0646\u064a.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/\u0642\u0627\u0644\u0628-\u062d\u064a\u0648\u0627\u0646\u064a-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/\u0642\u0627\u0644\u0628-\u062d\u064a\u0648\u0627\u0646\u064a-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/\u0642\u0627\u0644\u0628-\u062d\u064a\u0648\u0627\u0646\u064a-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><div class=\"wdt-media-image-cover-container\"><div class=\"wdt-content-button wdt-button-clone\"><a href=\"https:\/\/uae.mosesexport.com\/salt-for-animal-feed\/\"rel=\"nofollow\" ><div class=\"wdt-button-text\"><span>view<\/span><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/salt-for-animal-feed\/\"rel=\"nofollow\" >Sal para alimenta\u00e7\u00e3o animal<\/a><\/h5><\/div><div class=\"wdt-content-description\">O sal para alimenta\u00e7\u00e3o animal \u00e9 um complemento essencial \u00e0 alimenta\u00e7\u00e3o animal<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-d3c10f4\"><\/div><div class=\"wdt-carousel-arrow-pagination\"><div class=\"wdt-arrow-pagination-prev wdt-arrow-pagination-prev-d3c10f4\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-left\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 504C119 504 8 393 8 256S119 8 256 8s248 111 248 248-111 248-248 248zm28.9-143.6L209.4 288H392c13.3 0 24-10.7 24-24v-16c0-13.3-10.7-24-24-24H209.4l75.5-72.4c9.7-9.3 9.9-24.8.4-34.3l-11-10.9c-9.4-9.4-24.6-9.4-33.9 0L107.7 239c-9.4 9.4-9.4 24.6 0 33.9l132.7 132.7c9.4 9.4 24.6 9.4 33.9 0l11-10.9c9.5-9.5 9.3-25-.4-34.3z\"><\/path><\/svg><\/div><div class=\"wdt-arrow-pagination-next wdt-arrow-pagination-next-d3c10f4\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm-28.9 143.6l75.5 72.4H120c-13.3 0-24 10.7-24 24v16c0 13.3 10.7 24 24 24h182.6l-75.5 72.4c-9.7 9.3-9.9 24.8-.4 34.3l11 10.9c9.4 9.4 24.6 9.4 33.9 0L404.3 273c9.4-9.4 9.4-24.6 0-33.9L271.6 106.3c-9.4-9.4-24.6-9.4-33.9 0l-11 10.9c-9.5 9.6-9.3 25.1.4 34.4z\"><\/path><\/svg><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0088b4b elementor-widget__width-auto animated-fast center elementor-invisible elementor-widget elementor-widget-wdt-button\" data-id=\"0088b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:&quot;100&quot;,&quot;item_hover_background_color&quot;:&quot;#54595F&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-link wdt-button-style-default wdt-button-size-nm wdt-animation- wdt-button-icon-after\" id=\"wdt-button-0088b4b\"><a class=\"wdt-button\" href=\"https:\/\/uae.mosesexport.com\/product\/\"><div class=\"wdt-button-text\"><span>Ver todos os produtos<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40e19eb wdt-no-full-section elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"40e19eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5b7f85\" data-id=\"b5b7f85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7d2e58c elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"7d2e58c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b276241 animated-fast elementor-invisible\" data-id=\"b276241\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9685a5e start elementor-widget__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"9685a5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-9685a5e\"><div class=\"wdt-heading-subtitle-wrapper wdt-heading-align-1 \"><span class=\"wdt-heading-subtitle\">Fornecer suporte 24 horas por dia, 7 dias por semana<\/span><\/div><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Solu\u00e7\u00f5es Log\u00edsticas e Embalagens<\/span><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec79e9c animated-fast elementor-invisible\" data-id=\"ec79e9c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab06adb start elementor-widget__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"ab06adb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-ab06adb\"><h1 class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Moses Salt Co<\/span><\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bdb49ef elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bdb49ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a576fc7\" data-wdt-settings=\"{&quot;id&quot;:&quot;a576fc7&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"a576fc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af6eaa5 elementor-widget elementor-widget-image\" data-id=\"af6eaa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/Port-Agency-01-768x768-1.png\" class=\"attachment-large size-large wp-image-26916\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/Port-Agency-01-768x768-1.png 768w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/Port-Agency-01-768x768-1-100x100.png 100w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/Port-Agency-01-768x768-1-300x300.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/Port-Agency-01-768x768-1-600x600.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/Port-Agency-01-768x768-1-150x150.png 150w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41893da animated-fast elementor-invisible\" data-id=\"41893da\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06afe63 start wdt-cus-about1-iconbox wdt-cus-about1-iconbox-top elementor-widget__width-initial elementor-widget elementor-widget-wdt-icon-box\" data-id=\"06afe63\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#EDEDED&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#54595F&quot;,&quot;columns&quot;:&quot;1&quot;,&quot;columns_tablet&quot;:&quot;1&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-content-aside\" id=\"wdt-icon-box-06afe63\" data-settings=\"\"><div class=\"wdt-column-wrapper wdt-column-gap-custom \" data-column-settings=\"\" data-module-id=\"wdt-module-id-06afe63\" id=\"wdt-module-id-06afe63\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><i><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 100 100\" style=\"enable-background:new 0 0 100 100;\" xml:space=\"preserve\">\t<style type=\"text\/css\">\t.h2-about-01{fill:currentColor;fill-opacity:1;}\t<\/style>\t<g>\t\t<path class=\"h2-about-01\" d=\"M5.6,98.2c-0.9,0-1.7-0.7-1.7-1.7v-6.1c0-14.6,10.3-27.3,24.5-30.3c2.9-0.6,5.8-2,8.2-3.9l1.8-1.9  c0.6-0.6,1.7-0.7,2.4,0c0.6,0.6,0.7,1.7,0,2.4l-1.9,2c0,0-0.1,0.1-0.2,0.2c-2.9,2.3-6.2,3.9-9.7,4.7c-12.7,2.7-21.9,14.1-21.9,27  v6.1C7.2,97.5,6.4,98.2,5.6,98.2L5.6,98.2z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M94.5,98.4c-0.9,0-1.7-0.7-1.7-1.7v-6.3c0-13-8.9-24.1-21.5-27c-3.7-0.9-7.1-2.4-10.2-4.7L59.1,57  c-0.7-0.6-0.8-1.6-0.3-2.4c0.6-0.7,1.6-0.9,2.3-0.3l2,1.6c2.6,2,5.6,3.3,8.9,4.1c14.2,3.2,24.1,15.6,24.1,30.2v6.3  c0,0.9-0.7,1.7-1.7,1.7L94.5,98.4z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M50.1,83.6c-0.3,0-0.7-0.1-1-0.3C48.4,82.8,31.9,71,28.7,62.7c-0.3-0.9,0.1-1.8,0.9-2.1  c0.9-0.3,1.8,0.1,2.1,0.9c2.5,6.3,14.7,15.8,18.3,18.4c3.6-2.7,16-12.4,18.4-18.8c0.3-0.9,1.3-1.3,2.1-1s1.3,1.3,1,2.1  C68.4,70.7,51.7,82.8,51,83.3C50.7,83.5,50.4,83.6,50.1,83.6L50.1,83.6z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M23.4,97c-0.9,0-1.7-0.7-1.7-1.7v-8.7c0-0.9,0.7-1.7,1.7-1.7c0.9,0,1.7,0.7,1.7,1.7v8.7  C25,96.3,24.3,97,23.4,97z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M75.9,97c-0.9,0-1.7-0.7-1.7-1.7v-8.7c0-0.9,0.7-1.7,1.7-1.7s1.7,0.7,1.7,1.7v8.7C77.6,96.3,76.9,97,75.9,97z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M68.5,30.8H31.7c-2.1,0-3.8-1.7-3.8-3.8c0-2.1,1.7-3.8,3.8-3.8h36.8c2.1,0,3.8,1.7,3.8,3.8  C72.3,29,70.5,30.8,68.5,30.8z M31.7,26.4c0,0-0.5,0.2-0.5,0.5s0.2,0.5,0.5,0.5h36.8c0,0,0.5-0.2,0.5-0.5s-0.2-0.5-0.5-0.5H31.7z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M55.5,26.4H44.6c-0.9,0-1.7-0.7-1.7-1.7V6.5c0-2.6,2.2-4.8,4.8-4.8h4.4c2.6,0,4.8,2.2,4.8,4.8v18.3  C57.1,25.7,56.3,26.4,55.5,26.4L55.5,26.4z M46.3,23.1h7.5V6.5c0-0.9-0.7-1.5-1.5-1.5h-4.4c-0.9,0-1.5,0.7-1.5,1.5L46.3,23.1  L46.3,23.1z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M66.5,26.4H33.7c-0.9,0-1.7-0.7-1.7-1.7v-5c0-6.9,5.4-12.7,12.3-13.1C45.2,6.6,46,7.3,46,8.3  c0,0.9-0.6,1.7-1.6,1.7c-5.2,0.3-9.2,4.6-9.2,9.8v3.4h29.5v-3.4c0-5.3-4.1-9.6-9.4-9.8c-0.9,0-1.6-0.8-1.6-1.7  c0-0.9,0.7-1.6,1.7-1.6c7.1,0.3,12.6,6,12.6,13.1v5c0,0.9-0.7,1.7-1.7,1.7H66.5z\"><\/path>\t\t<path class=\"h2-about-01\" d=\"M50.1,54.2c-7.2,0-13.2-7.4-14.7-17.9c-0.1-0.9,0.5-1.7,1.4-1.9c0.9-0.1,1.7,0.5,1.9,1.4  c1.2,8.7,6,15.1,11.4,15.1s10.4-6.5,11.5-15.4c0.1-0.9,1-1.6,1.8-1.4c0.9,0.1,1.6,1,1.4,1.8C63.5,46.6,57.4,54.2,50.1,54.2  L50.1,54.2z\"><\/path>\t<\/g><\/svg><\/i><\/span><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Gest\u00e3o da cadeia de abastecimento<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">a gest\u00e3o do fluxo de bens e servi\u00e7os e inclui todos os processos que transformam mat\u00e9ria-prima em produtos finais<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fill\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.63 217.06L294.94 9.37C288.69 3.12 280.5 0 272.31 0s-16.38 3.12-22.62 9.37l-81.58 81.58L81.93 4.77c-6.24-6.25-16.38-6.25-22.62 0L36.69 27.38c-6.24 6.25-6.24 16.38 0 22.63l86.19 86.18-94.76 94.76c-37.49 37.49-37.49 98.26 0 135.75l117.19 117.19c18.75 18.74 43.31 28.12 67.87 28.12 24.57 0 49.13-9.37 67.88-28.12l221.57-221.57c12.49-12.5 12.49-32.76 0-45.26zm-116.22 70.97H65.93c1.36-3.84 3.57-7.98 7.43-11.83l13.15-13.15 81.61-81.61 58.61 58.6c12.49 12.49 32.75 12.49 45.24 0 12.49-12.49 12.49-32.75 0-45.24l-58.61-58.6 58.95-58.95 162.45 162.44-48.35 48.34z\"><\/path><\/svg><\/span><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Solu\u00e7\u00f5es de embalagem<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Oferecemos solu\u00e7\u00f5es de embalagem flex\u00edveis e eficazes que atendem \u00e0s necessidades de cada mercado ou categoria de clientes, para garantir que a qualidade do sal \u00e9 mantida e que \u00e9 f\u00e1cil de transportar e distribuir.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ship\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496.616 372.639l70.012-70.012c16.899-16.9 9.942-45.771-12.836-53.092L512 236.102V96c0-17.673-14.327-32-32-32h-64V24c0-13.255-10.745-24-24-24H248c-13.255 0-24 10.745-24 24v40h-64c-17.673 0-32 14.327-32 32v140.102l-41.792 13.433c-22.753 7.313-29.754 36.173-12.836 53.092l70.012 70.012C125.828 416.287 85.587 448 24 448c-13.255 0-24 10.745-24 24v16c0 13.255 10.745 24 24 24 61.023 0 107.499-20.61 143.258-59.396C181.677 487.432 216.021 512 256 512h128c39.979 0 74.323-24.568 88.742-59.396C508.495 491.384 554.968 512 616 512c13.255 0 24-10.745 24-24v-16c0-13.255-10.745-24-24-24-60.817 0-101.542-31.001-119.384-75.361zM192 128h256v87.531l-118.208-37.995a31.995 31.995 0 0 0-19.584 0L192 215.531V128z\"><\/path><\/svg><\/span><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Custo do seguro de frete (CIF)<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Oferecemos um servi\u00e7o de exporta\u00e7\u00e3o abrangente com cobertura \u201cCIF\u201d (Custo, Seguro e Frete), onde suportamos todos os custos associados ao envio do sal, incluindo o seguro das mercadorias e os custos de transporte do porto de exporta\u00e7\u00e3o para o porto designado do seu destino.<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><i><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 100 100\" style=\"enable-background:new 0 0 100 100;\" xml:space=\"preserve\">\t<style type=\"text\/css\">\t.h1-about-01{fill-opacity:1;}\t.h1-about-02{opacity:1;}\t<\/style>\t<g>\t\t<path class=\"h1-about-01\" d=\"M96.4,49.7h-4.4c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6h4.4c0.9,0,1.6,0.7,1.6,1.6  C98,49,97.3,49.7,96.4,49.7z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M96.4,56.2h-4.4c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6h4.4c0.9,0,1.6,0.7,1.6,1.6  C98,55.5,97.3,56.2,96.4,56.2z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M96.4,62.8h-4.4c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6h4.4c0.9,0,1.6,0.7,1.6,1.6  C98,62.1,97.3,62.8,96.4,62.8z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M96.4,69.4h-4.4c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6h4.4c0.9,0,1.6,0.7,1.6,1.6  C98,68.6,97.3,69.4,96.4,69.4z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M96.4,75.9h-4.4c-0.9,0-1.6-0.7-1.6-1.6s0.7-1.6,1.6-1.6h4.4c0.9,0,1.6,0.7,1.6,1.6S97.3,75.9,96.4,75.9z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M96.4,82.4h-4.4c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6h4.4c0.9,0,1.6,0.7,1.6,1.6  C98,81.7,97.3,82.4,96.4,82.4z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M96.4,89h-4.4c-0.9,0-1.6-0.7-1.6-1.6s0.7-1.6,1.6-1.6h4.4c0.9,0,1.6,0.7,1.6,1.6S97.3,89,96.4,89z\"><\/path>\t\t<g>\t\t\t<g class=\"h1-about-02\">\t\t\t\t<path d=\"M31.2,84.5c-0.4,0-0.9-0.2-1.1-0.5c-0.4-0.3-0.6-0.9-0.5-1.4l1-7.1c0-0.3,0.2-0.7,0.5-0.9l40.7-42.5    c0.6-0.7,1.6-0.7,2.3,0l6,5.8c0.3,0.3,0.5,0.7,0.5,1.1c0,0.5-0.2,0.9-0.5,1.2L39.4,82.8c0,0-0.6,0.4-0.9,0.5l-7,1.3    C31.5,84.5,31.2,84.5,31.2,84.5z M33.7,76.5l-0.6,4.3l4.3-0.8l39.2-40.9l-3.7-3.5L33.7,76.5z\"><\/path>\t\t\t<\/g>\t\t<\/g>\t\t<path class=\"h1-about-01\" d=\"M81.3,35.4c-0.4,0-0.8-0.2-1.1-0.5l-3-2.9c-0.6-0.6-0.7-1.6,0-2.3c0.6-0.7,1.6-0.7,2.3,0l3,2.9  c0.6,0.6,0.7,1.6,0,2.3C82.1,35.3,81.7,35.5,81.3,35.4L81.3,35.4z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M28.1,87.7c-0.4,0-0.8-0.2-1.1-0.5c-0.6-0.6-0.7-1.6,0-2.3l3.1-3.2c0.6-0.6,1.6-0.7,2.3,0  c0.6,0.6,0.7,1.6,0,2.3l-3.1,3.2C28.9,87.6,28.5,87.8,28.1,87.7L28.1,87.7z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M23.3,85.9H3.6c-0.9,0-1.6-0.7-1.6-1.6V17.3c0-0.5,0.2-0.9,0.5-1.2L14.8,3.8c0.3-0.3,0.7-0.5,1.2-0.5H61  c0.9,0,1.6,0.7,1.6,1.6V34c0,0.9-0.7,1.6-1.6,1.6c-0.9,0-1.6-0.7-1.6-1.6V6.6H16.6L5.3,18v64.7h18.1c0.9,0,1.6,0.7,1.6,1.6  C25,85.2,24.3,85.9,23.3,85.9L23.3,85.9z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M16,18.9H3.6c-0.7,0-1.2-0.4-1.5-1c-0.2-0.6-0.1-1.3,0.3-1.8L14.8,3.8c0.5-0.5,1.2-0.6,1.8-0.3  c0.6,0.2,1,0.9,1,1.5v12.3C17.6,18.2,16.8,18.9,16,18.9L16,18.9z M7.6,15.6h6.7V8.9L7.6,15.6z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M96.4,98.2h-64c-0.7,0-1.2-0.4-1.5-1c-0.2-0.6-0.1-1.3,0.3-1.8l64-64c0.5-0.5,1.2-0.6,1.8-0.3  c0.6,0.2,1,0.9,1,1.5v64C97.9,97.5,97.2,98.2,96.4,98.2L96.4,98.2z M36.3,94.9h58.5V36.4L36.3,94.9z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M85.3,88.7H56.8c-0.7,0-1.2-0.4-1.5-1c-0.2-0.6-0.1-1.3,0.3-1.8l28.6-28.6c0.5-0.5,1.2-0.6,1.8-0.3  c0.6,0.2,1,0.9,1,1.5v28.6C86.9,88,86.2,88.7,85.3,88.7L85.3,88.7z M60.8,85.4h22.9V62.4L60.8,85.4z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M51.9,18.9H31.2c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6h20.7c0.9,0,1.6,0.7,1.6,1.6  C53.5,18.1,52.8,18.9,51.9,18.9z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M51.9,29.3H10.3c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6H52c0.9,0,1.6,0.7,1.6,1.6  C53.6,28.6,52.9,29.3,51.9,29.3L51.9,29.3z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M51.9,35.6H10.3c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6H52c0.9,0,1.6,0.7,1.6,1.6  C53.6,34.9,52.9,35.6,51.9,35.6L51.9,35.6z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M51.9,42H10.3c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6H52c0.9,0,1.6,0.7,1.6,1.6  C53.6,41.3,52.9,42,51.9,42L51.9,42z\"><\/path>\t\t<path class=\"h1-about-01\" d=\"M32.3,48.3h-22c-0.9,0-1.6-0.7-1.6-1.6c0-0.9,0.7-1.6,1.6-1.6h22c0.9,0,1.6,0.7,1.6,1.6  C34,47.6,33.2,48.3,32.3,48.3z\"><\/path>\t<\/g><\/svg><\/i><\/span><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Certificados de qualidade<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Fornecemos certificados de an\u00e1lise para todos os nossos produtos para garantir os mais elevados n\u00edveis de qualidade e assegurar a sua conformidade com as normas internacionais e locais.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-214fc2e start elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wdt-button\" data-id=\"214fc2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-link wdt-button-style-default wdt-button-size-nm wdt-animation- wdt-button-icon-after\" id=\"wdt-button-214fc2e\"><a class=\"wdt-button\" href=\"https:\/\/uae.mosesexport.com\/contact\/\"><div class=\"wdt-button-text\"><span>Leia mais<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d8c02 start elementor-widget__width-auto elementor-widget-tablet__width-auto wdt-cont-style elementor-widget elementor-widget-wdt-icon-box\" data-id=\"33d8c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#02010100&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#11000000&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-title-meta-aside\" id=\"wdt-icon-box-33d8c02\"><div class=\"wdt-content-item\"><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-elements-group wdt-content-group \"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><i><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 55 53\" style=\"enable-background:new 0 0 55 53;\" xml:space=\"preserve\"><g>\t<g>\t\t<g class=\"wdt-cus-telephone\">\t\t\t<path d=\"M19.3,46c18.5,13.1,30.5,4.5,33.3-3.4c0.6-1.7-0.4-3.4-2.1-3.8c-3.3-0.8-6.8-2.7-9.8-4    c-1.4-0.6-3.1,0-3.8,1.4L34.6,40c-0.5,1-1.7,1.6-2.8,1.2c-2.7-0.8-6.6-2.8-12-8.2c-5.4-5.4-7.3-9.4-8.2-12    c-0.3-1.1,0.2-2.3,1.2-2.8l3.8-2.2c1.4-0.7,2-2.4,1.4-3.8c-1.4-3.1-3.3-6.5-4-9.8c-0.4-1.7-2.2-2.7-3.8-2.1    C2.3,3-6.3,15,6.8,33.5C10.2,38.4,14.5,42.6,19.3,46L19.3,46z\"><\/path>\t\t<\/g>\t<\/g>\t<g>\t\t<g>\t\t\t<path d=\"M28,26.2c-0.2,0-0.5,0-0.7-0.1c-0.7-0.3-1.1-0.9-1.1-1.6L26.1,7.9c0-1.5,0.6-2.8,1.6-3.9c1-1,2.4-1.6,3.8-1.6H49    c3,0,5.4,2.4,5.4,5.4v7.8c0,3-2.4,5.4-5.4,5.4H34.2l-5,4.7C28.9,26.1,28.4,26.2,28,26.2z M31.5,4.4c-0.9,0-1.8,0.4-2.4,1    c-0.6,0.7-1,1.5-1,2.4L28.2,24l4.9-4.7c0.2-0.2,0.4-0.3,0.7-0.3H49c1.9,0,3.4-1.5,3.4-3.4V7.8c0-1.9-1.5-3.4-3.4-3.4H31.5z\"><\/path>\t\t<\/g>\t\t<g>\t\t\t<path d=\"M42.2,12.2c0.4-1-0.1-2.2-1.1-2.7s-2.2,0.1-2.7,1.1c-0.4,1,0.1,2.2,1.1,2.7C40.5,13.7,41.7,13.2,42.2,12.2z\"><\/path>\t\t<\/g>\t\t<g>\t\t\t<path d=\"M34.4,12.2c0.4-1-0.1-2.2-1.1-2.7c-1-0.4-2.2,0.1-2.7,1.1c-0.4,1,0.1,2.2,1.1,2.7S34,13.2,34.4,12.2z\"><\/path>\t\t<\/g>\t\t<g>\t\t\t<path d=\"M48.5,13.4c1.1-0.3,1.8-1.4,1.5-2.4c-0.3-1.1-1.4-1.8-2.4-1.5c-1.1,0.3-1.8,1.4-1.5,2.4C46.3,13,47.4,13.6,48.5,13.4z\"><\/path>\t\t<\/g>\t<\/g><\/g><\/svg><\/i><\/span><\/div><\/div><div class=\"wdt-content-title-group below\"><div class=\"wdt-content-title\"><h5><a href=\"tel:+201050022225\">(20)01050022225<\/a><\/h5><\/div><span><\/span><div class=\"wdt-content-subtitle\">Ligue para fazer reserva<\/div><\/div><\/div><div class=\"wdt-content-separator separator-2\"><span><\/span><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35c0d44 animated-fast elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"35c0d44\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;background_background&quot;:&quot;video&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;100&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/uae.mosesexport.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/470096449_9357755297615807_2913029529188334827_n.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;background_video_end&quot;:1000,&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5429318\" data-id=\"5429318\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c85def elementor-section-full_width wdt-dark-bg elementor-section-height-default elementor-section-height-default\" data-id=\"1c85def\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8997078\" data-id=\"8997078\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ce9780b\" data-id=\"ce9780b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e4f6af center elementor-widget elementor-widget-wdt-heading\" data-id=\"3e4f6af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-3e4f6af\"><div class=\"wdt-heading-subtitle-wrapper wdt-heading-align-1 \"><span class=\"wdt-heading-subtitle\">Comece hoje<\/span><\/div><h2 class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Moses Company<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d76abf center elementor-widget elementor-widget-wdt-heading\" data-id=\"0d76abf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-0d76abf\"><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">As nossas f\u00e1bricas<\/span><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd779fd wdt-cus-home3-banner-title elementor-widget__width-initial center elementor-widget elementor-widget-wdt-heading\" data-id=\"dd779fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-dd779fd\"><div class=\"wdt-heading-content-wrapper\">Uma empresa eg\u00edpcia l\u00edder no fabrico e produ\u00e7\u00e3o dos melhores tipos de sal<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-63cf19c\" data-id=\"63cf19c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-837a033 animated-fast elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"837a033\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;100&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-200e5bb elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"200e5bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-387bbd3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"387bbd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"331\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/03\/house-img.png\" class=\"attachment-full size-full wp-image-5564\" alt=\"\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0847542\" data-id=\"0847542\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f967539 start wdt-cus-booking-banner elementor-widget elementor-widget-wdt-heading\" data-id=\"f967539\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-f967539\"><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Precisa de agendar a sua visita?<\/span><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d17e8e4 start elementor-widget-tablet__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"d17e8e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-d17e8e4\"><div class=\"wdt-heading-content-wrapper\">Convidamo-lo a visitar as nossas f\u00e1bricas para conhecer mais de perto os processos de produ\u00e7\u00e3o e aprender sobre a qualidade dos nossos produtos.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8d22314\" data-id=\"8d22314\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc3a9f2 elementor-widget__width-auto center elementor-widget elementor-widget-wdt-button\" data-id=\"cc3a9f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;item_normal_background_color&quot;:&quot;#FFC527&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-link wdt-button-style-default wdt-button-size-nm wdt-animation- wdt-button-icon-after\" id=\"wdt-button-cc3a9f2\"><a class=\"wdt-button\" href=\"#\"><div class=\"wdt-button-text\"><span>Obtenha uma cota\u00e7\u00e3o<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24495ec elementor-widget__width-auto center elementor-widget elementor-widget-wdt-button\" data-id=\"24495ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_color&quot;:&quot;#54595F&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-style-default wdt-button-size-nm wdt-animation- wdt-button-icon-after\" id=\"wdt-button-24495ec\"><a class=\"wdt-button\" ><div class=\"wdt-button-text\"><span>Reserve os seus servi\u00e7os<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5fb151 wdt-no-full-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5fb151\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29df49d animated-fast elementor-invisible\" data-id=\"29df49d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-131e2f1 elementor-section-full_width wdt-section-wrap-col elementor-section-height-default elementor-section-height-default\" data-id=\"131e2f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-47c1dfa\" data-id=\"47c1dfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4c304b elementor-widget elementor-widget-image\" data-id=\"b4c304b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"892\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/LOGO-M-blue-web-sait-\u0628\u062f\u0648\u0646-\u062e\u0644\u0641\u064a\u0629-1024x892.png\" class=\"attachment-large size-large wp-image-26929\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/LOGO-M-blue-web-sait-\u0628\u062f\u0648\u0646-\u062e\u0644\u0641\u064a\u0629-1024x892.png 1024w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/LOGO-M-blue-web-sait-\u0628\u062f\u0648\u0646-\u062e\u0644\u0641\u064a\u0629-1000x871.png 1000w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/LOGO-M-blue-web-sait-\u0628\u062f\u0648\u0646-\u062e\u0644\u0641\u064a\u0629-300x261.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/LOGO-M-blue-web-sait-\u0628\u062f\u0648\u0646-\u062e\u0644\u0641\u064a\u0629-768x669.png 768w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/LOGO-M-blue-web-sait-\u0628\u062f\u0648\u0646-\u062e\u0644\u0641\u064a\u0629-1536x1338.png 1536w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/LOGO-M-blue-web-sait-\u0628\u062f\u0648\u0646-\u062e\u0644\u0641\u064a\u0629-2048x1784.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f48538 elementor-widget elementor-widget-spacer\" data-id=\"0f48538\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bd1ed33 elementor-section-full_width wdt-section-wrap-col elementor-section-height-default elementor-section-height-default\" data-id=\"bd1ed33\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a3eddd\" data-id=\"5a3eddd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-865960c elementor-widget elementor-widget-wdt-heading\" data-id=\"865960c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-865960c\"><h4 class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Moses Salt Co<\/span><\/h4><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b88326c elementor-widget elementor-widget-wdt-heading\" data-id=\"b88326c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-b88326c\"><div class=\"wdt-heading-content-wrapper\">Uma empresa eg\u00edpcia l\u00edder no fabrico e produ\u00e7\u00e3o dos melhores tipos de sal<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c5a0c7f\" data-id=\"c5a0c7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-815f4bf elementor-widget__width-auto elementor-widget elementor-widget-wdt-button\" data-id=\"815f4bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;item_normal_background_color&quot;:&quot;#54595F&quot;,&quot;item_hover_background_color&quot;:&quot;#003057&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-button-holder wdt-template-filled wdt-button-link wdt-button-style-default wdt-button-size-nm wdt-animation- wdt-button-icon-after\" id=\"wdt-button-815f4bf\"><a class=\"wdt-button\" href=\"https:\/\/uae.mosesexport.com\/about\/\"><div class=\"wdt-button-text\"><span>Sobre n\u00f3s<\/span><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff75123 elementor-widget elementor-widget-spacer\" data-id=\"ff75123\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8eebd99 animated-fast elementor-invisible\" data-id=\"8eebd99\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-292aa84 start elementor-widget elementor-widget-wdt-heading\" data-id=\"292aa84\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-292aa84\"><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Perguntas frequentes<\/span><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dcd71d wdt-cus-accordion1 elementor-widget elementor-widget-wdt-accordion-and-toggle\" data-id=\"4dcd71d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-accordion-and-toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-accordion-toggle-holder wdt-module-toggle wdt-template-classic wdt-expand-collapse-position-end\" id=\"wdt-accordion-and-toggle-4dcd71d\"><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">Quem somos n\u00f3s?<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Somos uma empresa eg\u00edpcia l\u00edder no fabrico e produ\u00e7\u00e3o dos melhores tipos de sal desde a nossa funda\u00e7\u00e3o em 2017. O nosso objetivo \u00e9 fornecer produtos de sal de alta qualidade, incluindo sal-gema bruto, sal marinho, sal de cozinha, sal industrial, sal para purifica\u00e7\u00e3o de \u00e1gua, sal de inverno, sal animal e outros. Oferecemos artigos especializados.<\/div><\/div><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">Que tipos de sal exportam?<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Somos especializados na exporta\u00e7\u00e3o de v\u00e1rios tipos de sal, tais como: sal de cozinha, sal industrial, sal marinho, sal marinho rosa, sal-gema e outros.<\/div><\/div><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">Podem fornecer sal personalizado mediante solicita\u00e7\u00e3o?<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Sim, disponibilizamos o servi\u00e7o de personaliza\u00e7\u00e3o do sal de acordo com as necessidades do cliente, seja em termos de tamanho, tipo ou embalagem.<\/div><\/div><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">Enviam sal para todos os pa\u00edses?<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Sim, enviamos sal para v\u00e1rias partes do mundo, com envios personalizados para cada pa\u00eds de acordo com as necessidades.<\/div><\/div><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">O sal que exporta est\u00e1 sujeito a controlos de qualidade?<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Sim, seguimos elevados padr\u00f5es de qualidade e cada lote de sal \u00e9 inspecionado de acordo com os mais elevados padr\u00f5es de qualidade antes do envio.<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-722c5c9 wdt-no-full-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"722c5c9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecb24c0\" data-id=\"ecb24c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0c70332 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0c70332\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-77b7a92 animated-fast elementor-invisible\" data-id=\"77b7a92\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5dbe53 start elementor-widget elementor-widget-wdt-heading\" data-id=\"e5dbe53\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-e5dbe53\"><div class=\"wdt-heading-subtitle-wrapper wdt-heading-align-1 \"><span class=\"wdt-heading-subtitle\">As pessoas confiam<\/span><\/div><p class=\"wdt-heading-title-wrapper wdt-heading-align-1 wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Porque somos os melhores<\/span><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aef61a7 start elementor-widget-tablet__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"aef61a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-aef61a7\"><div class=\"wdt-heading-content-wrapper\">Somos os melhores gra\u00e7as \u00e0 elevada qualidade dos nossos produtos e aos nossos 10 anos de experi\u00eancia<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4dc9fa0 animated-fast elementor-invisible\" data-id=\"4dc9fa0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f9c2f3  wdt-cus-home1-quote-iconbox wdt-cus-our-policy center elementor-widget elementor-widget-wdt-icon-box\" data-id=\"7f9c2f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:&quot;50&quot;,&quot;sizes&quot;:[]},&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;slides_to_show_opts_tablet&quot;:&quot;1&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-ico-minimal\" id=\"wdt-icon-box-7f9c2f3\" data-id=\"7f9c2f3\" data-settings=\"\"><div class=\"wdt-icon-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:&quot;50&quot;,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:&quot;50&quot;,&quot;mobile&quot;:&quot;50&quot;,&quot;tablet&quot;:&quot;50&quot;}}\" id=\"wdt-icon-box-swiper-7f9c2f3\"><div class=\"wdt-icon-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group \"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><i><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 78 83\" style=\"enable-background:new 0 0 78 83;\" xml:space=\"preserve\">\t<style> .wdt-hands{stroke-width: 1.5px; stroke: currentColor;}<\/style>\t<path class=\"wdt-hands\" d=\"M10.7,55.5C10.7,55.5,10.7,55.5,10.7,55.5l8.2-18c0,0,0,0,0-0.1l0.8-1.7l-7.6-3.4l-9.5,21l7.6,3.4L10.7,55.5L10.7,55.5z  M47.5,37c0.4-0.6,0.9-1.2,1.3-1.8l0,0c0.5-0.8,0.9-1.6,1.4-2.4c1.3-2.7,2.3-5.7,3-9c0.6-3.1,0.9-6.4,0.8-9.9 c-1.4,0-2.9-0.1-4.4-0.3c-1.6-0.3-3.2-0.7-4.7-1.3c-1.3-0.5-2.5-1.2-3.7-2c-0.9-0.6-1.7-1.4-2.4-2.2c-0.7,0.8-1.6,1.6-2.4,2.2 c-1.2,0.8-2.4,1.5-3.7,2c-1.5,0.6-3.1,1-4.7,1.3c-1.5,0.2-3,0.3-4.4,0.3c0,3.4,0.2,6.7,0.8,9.9c0.6,3.3,1.6,6.3,3,9 c0.4,0.9,0.9,1.7,1.4,2.5c0.4,0.6,0.8,1.3,1.3,1.9l3.3-1v0l0,0c0.8-0.2,1.2-0.3,1.7-0.3c0.5,0,1,0.1,1.7,0.4c0,0,0,0,0.1,0l1.9,0.9 l0.4-0.2c0.4-0.1,0.6-0.2,0.7-0.3c2.9-1.1,3-1,6.1-0.1l0.7,0.2C47,36.8,47.3,36.9,47.5,37L47.5,37z M28.8,37.5 c-0.4-0.5-0.7-1-1.1-1.6c-0.5-0.8-1-1.7-1.5-2.6c-1.4-2.8-2.4-6-3.1-9.3c-0.7-3.4-0.9-7.1-0.9-10.8l0-0.7l0.7,0 c1.5,0.1,3.1,0,4.8-0.3c1.5-0.2,2.9-0.6,4.4-1.2c1.2-0.5,2.3-1.1,3.4-1.9c1-0.7,1.9-1.6,2.7-2.6L38.8,6l0.5,0.6 c0.8,1,1.7,1.9,2.7,2.6c1.1,0.8,2.2,1.4,3.4,1.9c1.4,0.6,2.9,1,4.4,1.2c1.7,0.3,3.3,0.3,4.8,0.3l0.7,0l0,0.7 c0.1,3.8-0.2,7.4-0.9,10.8c-0.7,3.4-1.7,6.5-3.1,9.3c-0.4,0.9-0.9,1.7-1.4,2.5v0c-0.3,0.5-0.6,1-1,1.5c0.4,0.1,0.9,0.2,1.3,0.3 c1,0.2,2,0.4,3.1,0.5c1.1,0.1-0.3,0,0.5,0.1c1.1,0.1,1.6,0.2,2,0.1c0.4-0.1,0.8-0.3,1.5-0.7l0.3-0.2l-0.8-1.8c0,0,0,0,0-0.1 c-0.1-0.3,0-0.7,0.3-0.9l8.8-4l0,0c0.3-0.1,0.7,0,0.9,0.3l10.1,22.2c0,0,0,0,0,0.1c0.1,0.3,0,0.7-0.3,0.9l-8.8,4v0 c-0.3,0.1-0.7,0-0.9-0.3l-0.5-1.2l-5.5,3c0.3,0.6,0.4,1.3,0.3,1.9c-0.1,0.9-0.5,1.7-1.1,2.4c-1.1,1.1-2.3,1.3-3.4,1.1 c-0.3-0.1-0.6-0.2-0.8-0.3c0,0.1,0,0.2,0,0.3c0,1-0.4,1.9-1.1,2.7c-0.8,0.8-1.8,1.2-2.8,1.1c-0.3,0-0.6-0.1-0.8-0.1 c0,0.2,0,0.4,0,0.6c0,1-0.4,2-1.1,2.8c-0.8,0.8-1.7,1.1-2.7,1.1c-0.5,0-0.9-0.1-1.4-0.3c0,0.1,0,0.2,0,0.3c0,1-0.4,1.9-1.1,2.6 C44,76.7,43,77,42,77c-1,0-2-0.4-2.7-1.2l-0.2-0.2l-0.2,0.2c-0.8,0.8-1.7,1.1-2.7,1.1s-2-0.4-2.7-1.1c-0.7-0.7-1.1-1.7-1.1-2.7 c-0.6,0.4-1.3,0.5-2,0.5c-1,0-2-0.4-2.7-1.1c-0.7-0.8-1.1-1.8-1.1-2.8c0-0.2,0-0.4,0-0.6c-0.3,0.1-0.6,0.1-0.9,0.1 c-1,0-1.9-0.4-2.7-1.1c0,0,0,0,0,0v0c-0.7-0.8-1.1-1.8-1.1-2.8c0-0.1,0-0.2,0-0.3c-0.4,0.1-0.9,0.2-1.3,0.2v0c-1,0-2-0.4-2.7-1.1 c-0.7-0.7-1-1.5-1.1-2.4v0c-0.1-0.7,0-1.3,0.3-1.9l-5.4-3.1l-0.5,1.1l0,0c-0.1,0.3-0.5,0.5-0.9,0.3l-8.8-4l0,0l0,0 c-0.3-0.2-0.5-0.5-0.3-0.9l10.1-22.2l0,0c0.1-0.3,0.5-0.5,0.9-0.3l8.8,4v0l0,0c0.3,0.2,0.5,0.5,0.3,0.9l-0.8,1.8l0.9,0.5 c0,0,0,0,0,0c0,0,0.2,0.1,0.3,0.2c0.4,0.2,0.5,0.3,1.3,0.2l3.4-0.4c0.6-0.1,1-0.1,1.5-0.2C28.1,37.7,28.4,37.6,28.8,37.5L28.8,37.5z  M12.2,55.5l5.5,3.2c0,0,0.1-0.1,0.1-0.1l3.8-3.9c0.8-0.8,1.7-1.1,2.7-1.1s2,0.4,2.7,1.1c0.7,0.8,1.1,1.8,1.1,2.8c0,0.1,0,0.2,0,0.3 c0.4-0.2,0.9-0.2,1.3-0.2c1,0,2,0.4,2.7,1.1c0.7,0.8,1.1,1.8,1.1,2.8c0,0.2,0,0.4,0,0.6c0.3-0.1,0.6-0.1,0.9-0.1c1,0,2,0.4,2.7,1.1 c0.7,0.8,1.1,1.8,1.1,2.8c0,0.1,0,0.2,0,0.3c0.4-0.1,0.8-0.2,1.2-0.2c1,0,2,0.4,2.7,1.1c0.2,0.2,0.4,0.4,0.5,0.7 c0.1,0.2,0.2,0.4,0.3,0.6l2,2l0,0c0,0,0.1,0.1,0.1,0.1l0.6,0.6c0.5,0.5,1.1,0.8,1.8,0.8c0.6,0,1.3-0.2,1.8-0.7 c0.5-0.5,0.7-1.1,0.7-1.8c0-0.7-0.2-1.3-0.7-1.8l-3.6-3.6c-0.3-0.3-0.3-0.7,0-0.9c0.3-0.3,0.7-0.3,0.9,0l3.7,3.6 c0.6,0.6,1.3,0.9,1.9,0.9c0.6,0,1.3-0.2,1.8-0.7c0.5-0.5,0.7-1.1,0.7-1.8c0-0.6-0.2-1.3-0.6-1.8l-3.7-3.7c-0.3-0.3-0.3-0.7,0-0.9 c0.3-0.3,0.7-0.3,0.9,0l3.7,3.7c0.7,0.7,1.4,1.3,2.2,1.4h0c0.7,0.2,1.4,0,2.1-0.7c0.4-0.4,0.7-1,0.7-1.6c0.1-0.6-0.1-1.2-0.4-1.7 c-2.5-2.6-5.4-5.1-8.3-7.4c-2.9-2.2-5.9-4.2-8.9-5.8c-0.5-0.3-0.8-0.5-1.1-0.6c-0.2-0.1-0.3-0.2-0.4-0.2c-0.1,0-0.4,0.1-1.1,0.4 l-0.1,0c-1.5,0.6-1.8,1.2-2.3,2.4c-0.2,0.4-0.4,0.8-0.6,1.4c-0.2,0.4-0.4,0.8-0.7,1.1c-0.8,1-1.8,1.8-2.9,2.2 c-1.1,0.4-2.4,0.3-3.5-0.3c-0.3-0.1-0.5-0.3-0.8-0.5c0,0,0,0,0,0c-0.5-0.5-0.7-1-0.7-1.7c0-0.6,0.1-1.2,0.3-1.9l0.2-1.1 c0.9-3.9,1.3-5.8,2.4-7.1c1-1.2,2.5-1.7,5.4-2.7l0.7-0.2l-0.7-0.3c-0.5-0.2-0.8-0.3-1.2-0.3c-0.4,0-0.8,0.1-1.4,0.3l-4.2,1.3 c-0.6,0.2-1.1,0.3-1.6,0.4c-0.5,0.1-1,0.2-1.6,0.3l-3.4,0.4c-1.2,0.1-1.4,0-2.1-0.4c0,0-0.1-0.1-0.3-0.2c0,0,0,0,0,0l-0.9-0.5 L12.2,55.5L12.2,55.5z M18.4,59.9C18.4,60,18.4,60,18.4,59.9c-0.3,0.5-0.5,1.1-0.4,1.7c0.1,0.6,0.3,1.1,0.7,1.6 c0.5,0.5,1.1,0.7,1.8,0.7v0c0.6,0,1.3-0.3,1.8-0.8l3.9-4c0.5-0.5,0.7-1.1,0.7-1.8c0-0.7-0.2-1.3-0.7-1.8c-0.5-0.5-1.1-0.7-1.8-0.7 c-0.6,0-1.3,0.2-1.8,0.7l-3.8,3.9c-0.1,0.1-0.1,0.1-0.2,0.2C18.5,59.8,18.5,59.9,18.4,59.9L18.4,59.9z M27.7,59.6l-3.9,4 c-0.5,0.5-0.7,1.1-0.7,1.8c0,0.7,0.2,1.3,0.7,1.8c0,0,0,0,0,0c0.5,0.5,1.1,0.7,1.8,0.7c0.6,0,1.3-0.3,1.8-0.7l0.2-0.2c0,0,0,0,0,0 c1.6-1.6,0.9-0.9,1.8-1.8l1.8-1.8c0.5-0.5,0.7-1.2,0.7-1.8c0-0.7-0.2-1.3-0.7-1.8c-0.5-0.5-1.1-0.7-1.8-0.7S28.2,59.1,27.7,59.6 L27.7,59.6z M32.2,64.2l-1.8,1.9c-2.1,2.1-1.5,1.5-1.8,1.8c0,0,0,0,0,0L28.5,68c-0.4,0.5-0.7,1.1-0.7,1.8c0,0.7,0.2,1.3,0.7,1.8 c0.5,0.5,1.1,0.7,1.8,0.7c0.6,0,1.3-0.2,1.8-0.7l3.9-4c0.4-0.5,0.7-1.1,0.7-1.7c0-0.6-0.2-1.3-0.7-1.8c-0.5-0.5-1.1-0.7-1.8-0.7 s-1.3,0.3-1.8,0.7c0,0,0,0,0,0L32.2,64.2L32.2,64.2z M37.5,68.1l-3.1,3.2c-0.5,0.5-0.7,1.1-0.7,1.8c0,0.7,0.2,1.3,0.7,1.8 c0.5,0.5,1.1,0.7,1.8,0.7c0.7,0,1.3-0.3,1.8-0.7l3.1-3.1c0.4-0.4,0.6-0.8,0.7-1.3c0.1-0.5,0.1-1-0.1-1.5c-0.1-0.2-0.1-0.3-0.2-0.5 c-0.1-0.1-0.2-0.3-0.3-0.4c-0.5-0.5-1.1-0.7-1.8-0.7C38.6,67.3,38,67.6,37.5,68.1L37.5,68.1z M43.9,71.3l-0.8-0.8c0,0.1,0,0.1,0,0.2 c-0.2,0.7-0.5,1.4-1,1.9l-2,2l0.2,0.2c0.5,0.5,1.2,0.8,1.8,0.8c0.6,0,1.3-0.2,1.8-0.7c0.5-0.5,0.7-1.1,0.8-1.7 c0-0.6-0.2-1.3-0.6-1.8C44,71.5,43.9,71.4,43.9,71.3C43.9,71.4,43.9,71.4,43.9,71.3z M51.9,51.4c2.9,2.2,5.7,4.7,8.2,7.2l5.7-3.1 l-7.6-16.8L58,38.8c-0.9,0.5-1.3,0.7-1.9,0.9c-0.6,0.1-1.2,0-2.4-0.1c-0.4-0.1,1,0.1-0.5-0.1c-1.1-0.1-2.1-0.3-3.2-0.5 c-1.1-0.2-2.2-0.5-3.5-0.9c-0.5-0.1-0.6-0.2-0.7-0.2c-2.6-0.8-2.8-0.8-5.2,0.1c-0.4,0.2-0.6,0.2-0.8,0.3L39,38.5 c-0.9,0.3-1.6,0.6-2.2,0.8c-2.6,0.9-4,1.4-4.8,2.3c-0.9,1-1.3,2.8-2.1,6.5l-0.2,1.1c-0.1,0.6-0.2,1.2-0.2,1.6c0,0.3,0.1,0.5,0.3,0.7 c0.2,0.1,0.4,0.3,0.5,0.3c0.8,0.4,1.7,0.5,2.5,0.2h0c0.8-0.3,1.6-0.9,2.2-1.7c0.2-0.3,0.4-0.6,0.6-0.9c0.2-0.5,0.4-0.9,0.6-1.3 c0.7-1.5,1-2.3,3-3.1l0.1,0c0.9-0.4,1.3-0.5,1.8-0.5c0.3,0,0.5,0.2,0.9,0.4c0.2,0.1,0.5,0.3,1,0.6C45.9,47.1,49,49.1,51.9,51.4 L51.9,51.4z M67.3,55.5l0.5,1.2l7.6-3.4l-9.5-21l-7.6,3.4L67.3,55.5C67.3,55.5,67.3,55.5,67.3,55.5z M32.4,23.7l4.1,4.1l8.6-8.8 l2.4,2.4l-11,11.2L30,26.1L32.4,23.7L32.4,23.7z\"><\/path><\/svg><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Relacionamentos distintos<\/h5><\/div><div class=\"wdt-content-description\">Constru\u00edmos rela\u00e7\u00f5es de longo prazo com os nossos clientes baseadas na confian\u00e7a e transpar\u00eancia<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group \"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><i><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 78 83\" style=\"enable-background:new 0 0 78 83;\" xml:space=\"preserve\"><g class=\"wdt-cus-thumbsup\">\t<g>\t\t<path d=\"M21.9,75.3H15c-1.6,0-3-1.3-3-3V45.9c0-1.6,1.3-3,3-3h6.9c2.7,0,4.8,2.2,4.8,4.8v22.7C26.7,73.2,24.5,75.3,21.9,75.3z    M15,46v26.4l6.9,0c1,0,1.8-0.8,1.8-1.8V47.8c0-1-0.8-1.8-1.8-1.8H15z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M45.5,75.1c-7.5,0-17.1-1.5-20-1.9c-1.1-0.2-1.8-1.1-1.8-2.2V47c0-1,0.7-1.9,1.8-2.2c2.7-0.5,4-2.7,5.7-5.4   c0.7-1.1,1.3-2.2,2.2-3.3c0.5-0.7,1-1.3,1.5-1.9c2.4-3,4.3-5.4,5-9.2c0.3-1.6,0.5-2.7,0.6-3.5c0.2-1.3,0.3-2,0.9-2.6   c1.2-1.2,5.1-0.6,6.2,0.1c2.2,1.3,3.4,4.4,3.4,8.7c0,4-0.9,5.4-2.4,8l-0.5,0.8c-0.6,1-0.9,2.9-0.8,3.6c0.6,0.1,1.8,0,2.9-0.1   c2-0.2,4.7-0.4,7.9-0.1c4.9,0.4,7,1.3,7.3,6c0.2,2.3-0.7,3.5-1.4,4.2c0.7,0.7,1.7,1.8,1.7,3.7c0,2.1-1.4,3.3-2.2,4   c0,0-0.1,0.1-0.1,0.1c0.6,0.7,1.6,2,1,4.6c-0.6,2.3-1.9,3.1-2.7,3.6c-0.1,0.1-0.2,0.1-0.3,0.2c0,0,0,0.1,0,0.2   c0.2,0.7,0.3,1.5,0.1,3.2c-0.7,3.8-8,5.2-14.6,5.4C46.4,75.1,46,75.1,45.5,75.1z M26.7,70.3c3.6,0.6,13.1,1.9,20,1.8   c8.3-0.2,11.5-2.2,11.7-2.9c0.2-1.2,0.1-1.6,0-2c-0.1-0.4-0.2-0.9-0.1-1.7c0.2-1,1-1.5,1.6-1.9c0.6-0.4,1.2-0.7,1.4-1.8   c0.3-1.3,0-1.6-0.4-2c-0.4-0.4-1-1-0.9-2.1c0.1-1,0.8-1.7,1.4-2.2c0.7-0.6,1.2-1,1.2-1.7c0-0.8-0.4-1.2-0.9-1.7   c-0.5-0.4-1.1-1-1.1-2c0-1,0.6-1.6,1.1-1.9c0.5-0.4,0.9-0.8,0.8-2c-0.2-2.5-0.2-2.9-4.5-3.2c-3-0.2-5.5,0-7.5,0.1   c-2.3,0.2-3.7,0.3-4.8-0.3c-0.4-0.2-0.9-0.7-1.1-1.6c-0.4-1.7,0.2-4.7,1.1-6.2l0.5-0.8c1.4-2.4,2-3.3,2-6.4c0-3.4-1-5.5-2-6.1   c-0.4-0.2-1.8-0.4-2.5-0.4c0,0.2-0.1,0.5-0.1,0.8c-0.1,0.8-0.3,1.9-0.6,3.6c-0.9,4.5-3.1,7.3-5.6,10.5c-0.5,0.6-1,1.2-1.5,1.9   c-0.7,1-1.4,2-2,3.1c-1.7,2.8-3.4,5.7-7,6.7V70.3z M43.2,21.3L43.2,21.3L43.2,21.3z M43.7,20.9L43.7,20.9L43.7,20.9z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M43.3,43.5c-1,0-2-0.1-3.1-0.3c-0.8-0.2-1.3-1-1.1-1.8c0.2-0.8,1-1.3,1.8-1.1c1.6,0.4,3.4,0.2,5,0.1   c0.5-0.1,1.1-0.1,1.6-0.1c0.8,0,1.5,0.6,1.6,1.4c0,0.8-0.6,1.5-1.4,1.6c-0.5,0-1,0.1-1.5,0.1C45.3,43.4,44.3,43.5,43.3,43.5z\"><\/path>\t<\/g><\/g><g class=\"wdt-cus-thumbsup-rays\">\t<g>\t\t<path d=\"M44.3,15.2c-0.8,0-1.5-0.7-1.5-1.5V9c0-0.8,0.7-1.5,1.5-1.5s1.5,0.7,1.5,1.5v4.7C45.8,14.5,45.2,15.2,44.3,15.2z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M37.3,17.9c-0.4,0-0.8-0.1-1.1-0.4l-3.3-3.3c-0.6-0.6-0.6-1.5,0-2.1c0.6-0.6,1.5-0.6,2.1,0l3.3,3.3c0.6,0.6,0.6,1.5,0,2.1   C38.1,17.8,37.7,17.9,37.3,17.9z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M51.4,17.9c-0.4,0-0.8-0.1-1.1-0.4c-0.6-0.6-0.6-1.5,0-2.1l3.3-3.3c0.6-0.6,1.5-0.6,2.1,0c0.6,0.6,0.6,1.5,0,2.1l-3.3,3.3   C52.2,17.8,51.8,17.9,51.4,17.9z\"><\/path>\t<\/g><\/g><\/svg><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Credibilidade e transpar\u00eancia<\/h5><\/div><div class=\"wdt-content-description\">Estamos interessados \u200b\u200bem fornecer certificados de an\u00e1lise para garantir que cada um dos nossos produtos cumpre os mais elevados padr\u00f5es de qualidade<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-elements-group wdt-media-group \"><div class=\"wdt-content-icon-wrapper\"><div class=\"wdt-content-icon\"><span><i><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 78 83\" style=\"enable-background:new 0 0 78 83;\" xml:space=\"preserve\"><g class=\"wdt-cus-clock1\">\t<g>\t\t<path d=\"M69,43.9c0,8.3-3.4,15.8-8.8,21.3C54.8,70.6,47.3,74,39,74c-8.3,0-15.8-3.4-21.2-8.8c-2.7-2.7-4.9-6-6.4-9.7   C9.8,51.9,9,47.9,9,43.9c0-8,3.1-15.3,8.2-20.7c2.5-2.6,5.4-4.8,8.7-6.4c3.3-1.6,6.9-2.6,10.7-2.9V18c-2,0.2-4,0.6-5.9,1.3   c-2.1,0.7-4.2,1.7-6,3l0,0l-0.5,0.4l0,0h0c-3.4,2.4-6.2,5.6-8.1,9.3c-1.9,3.6-2.9,7.7-2.9,12c0,7.2,2.9,13.7,7.6,18.4   c4.7,4.7,11.2,7.6,18.4,7.6c7.2,0,13.6-2.9,18.3-7.6c4.7-4.7,7.6-11.2,7.6-18.4c0-0.6,0.3-1,0.6-1.4c0.4-0.4,0.9-0.6,1.4-0.6   c0.6,0,1.1,0.2,1.4,0.6C68.8,42.9,69,43.3,69,43.9z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M35.3,15.2V9.1c0,0,0-0.1,0.1-0.1c0,0,0.1,0,0.1,0l9.5,6l0.1,0c0,0,0.1,0.1,0.1,0.1c0,0.1,0,0.1-0.1,0.1l-0.1,0l-9.5,6   c0,0-0.1,0-0.1,0c0,0-0.1-0.1-0.1-0.1V15.2z\"><\/path>\t<\/g><\/g><g class=\"wdt-cus-clock2\">\t<g>\t\t<path d=\"M27.3,33c0.6-0.6,1.6-0.6,2.2,0l10.2,10.2c0.6,0.6,0.6,1.6,0,2.2c-0.6,0.6-1.6,0.6-2.2,0L27.3,35.2   C26.7,34.6,26.7,33.6,27.3,33z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M60.6,22.2c0.6,0.6,0.6,1.6,0,2.2L39.7,45.4c-0.6,0.6-1.6,0.6-2.2,0c-0.6-0.6-0.6-1.6,0-2.2l20.9-20.9   C59,21.6,60,21.6,60.6,22.2L60.6,22.2z\"><\/path>\t<\/g><\/g><g class=\"wdt-cus-clock3\">\t<g>\t\t<path d=\"M39.8,21.8v4.4c0,0.4-0.3,0.8-0.8,0.8c-0.4,0-0.8-0.3-0.8-0.8v-4.4c0-0.4,0.3-0.8,0.8-0.8C39.4,21,39.8,21.4,39.8,21.8z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M16.9,43.2h4.4c0.4,0,0.8,0.3,0.8,0.8c0,0.4-0.3,0.8-0.8,0.8h-4.4c-0.4,0-0.8-0.3-0.8-0.8C16.2,43.5,16.5,43.2,16.9,43.2z   \"><\/path>\t<\/g>\t<g>\t\t<path d=\"M38.2,66v-4.4c0-0.4,0.3-0.8,0.8-0.8c0.4,0,0.8,0.3,0.8,0.8V66c0,0.4-0.3,0.8-0.8,0.8C38.6,66.8,38.2,66.5,38.2,66z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M61.1,44.7h-4.4c-0.4,0-0.8-0.3-0.8-0.8c0-0.4,0.3-0.8,0.8-0.8h4.4c0.4,0,0.8,0.3,0.8,0.8C61.8,44.3,61.5,44.7,61.1,44.7z   \"><\/path>\t<\/g>\t<g>\t\t<path d=\"M28.6,24.4l1.2,2c0.2,0.4,0.1,0.8-0.3,1c-0.4,0.2-0.8,0.1-1-0.3l-1.2-2c-0.2-0.4-0.1-0.8,0.3-1C28,23.9,28.4,24,28.6,24.4   z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M20.3,32.2l2,1.2c0.4,0.2,0.5,0.7,0.3,1c-0.2,0.4-0.7,0.5-1,0.3l-2-1.2c-0.4-0.2-0.5-0.7-0.3-1   C19.5,32.1,19.9,32,20.3,32.2z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M19.5,54.3l2-1.2c0.4-0.2,0.8-0.1,1,0.3c0.2,0.4,0.1,0.8-0.3,1l-2,1.2c-0.4,0.2-0.8,0.1-1-0.3C19,55,19.2,54.5,19.5,54.3z   \"><\/path>\t<\/g>\t<g>\t\t<path d=\"M27.3,62.7l1.2-2c0.2-0.4,0.7-0.5,1-0.3c0.4,0.2,0.5,0.7,0.3,1l-1.2,2c-0.2,0.4-0.7,0.5-1,0.3   C27.2,63.5,27.1,63.1,27.3,62.7z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M49.4,63.5l-1.2-2c-0.2-0.4-0.1-0.8,0.3-1c0.4-0.2,0.8-0.1,1,0.3l1.2,2c0.2,0.4,0.1,0.8-0.3,1S49.6,63.8,49.4,63.5z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M57.7,55.6l-2-1.2c-0.4-0.2-0.5-0.7-0.3-1c0.2-0.4,0.7-0.5,1-0.3l2,1.2c0.4,0.2,0.5,0.7,0.3,1   C58.6,55.7,58.1,55.9,57.7,55.6z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M58.5,33.5l-2,1.2c-0.4,0.2-0.8,0.1-1-0.3c-0.2-0.4-0.1-0.8,0.3-1l2-1.2c0.4-0.2,0.8-0.1,1,0.3   C59,32.8,58.8,33.3,58.5,33.5z\"><\/path>\t<\/g>\t<g>\t\t<path d=\"M50.7,25.1l-1.2,2c-0.2,0.4-0.7,0.5-1,0.3c-0.4-0.2-0.5-0.7-0.3-1l1.2-2c0.2-0.4,0.7-0.5,1-0.3   C50.8,24.3,50.9,24.8,50.7,25.1z\"><\/path>\t<\/g><\/g><\/svg><\/i><\/span><\/div><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Servi\u00e7os oportunos<\/h5><\/div><div class=\"wdt-content-description\">Estamos sempre empenhados em entregar os seus pedidos a tempo, garantindo os mais altos n\u00edveis de qualidade e efici\u00eancia<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-7f9c2f3\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea8a97b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ea8a97b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e4acbf animated-fast elementor-invisible\" data-id=\"6e4acbf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-895e6a1 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"895e6a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-4d53bf8 e-con-full e-flex e-con e-parent\" data-id=\"4d53bf8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-242f497 center elementor-widget elementor-widget-wdt-advanced-carousel\" data-id=\"242f497\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;4&quot;,&quot;slides_to_scroll_opts&quot;:&quot;all&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-advanced-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-advanced-carousel-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-standard\" id=\"wdt-advanced-carousel-242f497\" data-id=\"242f497\" data-settings=\"\"><div class=\"wdt-advanced-carousel-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;4&quot;,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;&quot;,&quot;centered_slides&quot;:&quot;&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:20,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:2},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:4,&quot;toscroll&quot;:4}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:20,&quot;mobile&quot;:20,&quot;tablet&quot;:20}}\" id=\"wdt-advanced-carousel-swiper-242f497\"><div class=\"wdt-advanced-carousel-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-title\"><\/div><div class=\"wdt-content-sub-title\"><\/div><style><\/style>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"7020\" class=\"elementor elementor-7020\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6504772 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6504772\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d1f334\" data-id=\"0d1f334\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4e0d1c wdt-cus-before-after-slider elementor-widget elementor-widget-wdt-before-after-slider\" data-id=\"e4e0d1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-before-after-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t <div class=\"wdt-before-after-slider-container\">  <div class=\"wdt-img wdt-background-img\">  <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-after\">Before<\/span> <\/div> <div class=\"wdt-img wdt-foreground-img\" style=\"clip-path: inset(0 0 0 50%);\"> <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-before\">After<\/span> <\/div><input type=\"range\" min=\"0\" max=\"100\" value=\"50\" class=\"wdt-before-after-sliders\" name=\"wdt_before_after_slider\" id=\"wdt_before_after_slider_e4e0d1c\"> <div class=\"wdt-slider-button\"><span>Drag<\/span> <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-title\"><\/div><div class=\"wdt-content-sub-title\"><\/div><style>.elementor-7038 .elementor-element.elementor-element-eedeba4 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-7038 .elementor-element.elementor-element-eedeba4{width:auto;max-width:auto;}<\/style>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"7038\" class=\"elementor elementor-7038\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6504772 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6504772\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d1f334\" data-id=\"0d1f334\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eedeba4 wdt-cus-before-after-slider elementor-widget__width-auto elementor-widget elementor-widget-wdt-before-after-slider\" data-id=\"eedeba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-before-after-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t <div class=\"wdt-before-after-slider-container\">  <div class=\"wdt-img wdt-background-img\">  <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0637\u0639\u0627\u0645.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-after\">Before<\/span> <\/div> <div class=\"wdt-img wdt-foreground-img\" style=\"clip-path: inset(0 0 0 50%);\"> <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2024\/12\/\u0627\u0642\u0631\u0627\u0635.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-before\">After<\/span> <\/div><input type=\"range\" min=\"0\" max=\"100\" value=\"50\" class=\"wdt-before-after-sliders\" name=\"wdt_before_after_slider\" id=\"wdt_before_after_slider_eedeba4\"> <div class=\"wdt-slider-button\"><span>Drag<\/span> <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-title\"><\/div><div class=\"wdt-content-sub-title\"><\/div><style><\/style>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"7037\" class=\"elementor elementor-7037\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6504772 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6504772\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d1f334\" data-id=\"0d1f334\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd22965 wdt-cus-before-after-slider elementor-widget elementor-widget-wdt-before-after-slider\" data-id=\"dd22965\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-before-after-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t <div class=\"wdt-before-after-slider-container\">  <div class=\"wdt-img wdt-background-img\">  <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-after\">Before<\/span> <\/div> <div class=\"wdt-img wdt-foreground-img\" style=\"clip-path: inset(0 0 0 50%);\"> <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-0.2.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-before\">After<\/span> <\/div><input type=\"range\" min=\"0\" max=\"100\" value=\"50\" class=\"wdt-before-after-sliders\" name=\"wdt_before_after_slider\" id=\"wdt_before_after_slider_dd22965\"> <div class=\"wdt-slider-button\"><span>Drag<\/span> <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-title\"><\/div><div class=\"wdt-content-sub-title\"><\/div><style><\/style>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"7053\" class=\"elementor elementor-7053\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6504772 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6504772\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d1f334\" data-id=\"0d1f334\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e11acb wdt-cus-before-after-slider elementor-widget elementor-widget-wdt-before-after-slider\" data-id=\"7e11acb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-before-after-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t <div class=\"wdt-before-after-slider-container\">  <div class=\"wdt-img wdt-background-img\">  <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/\u0632\u0631\u0627\u0639\u064a-1-3.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-after\">Before<\/span> <\/div> <div class=\"wdt-img wdt-foreground-img\" style=\"clip-path: inset(0 0 0 50%);\"> <img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/\u0642\u0627\u0644\u0628-\u062d\u064a\u0648\u0627\u0646\u064a.png\" alt=\"\" title=\"\"><span class=\"wdt-before-after-slider-span-before\">After<\/span> <\/div><input type=\"range\" min=\"0\" max=\"100\" value=\"50\" class=\"wdt-before-after-sliders\" name=\"wdt_before_after_slider\" id=\"wdt_before_after_slider_7e11acb\"> <div class=\"wdt-slider-button\"><span>Drag<\/span> <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-242f497\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vamos trabalhar Exporta\u00e7\u00e3o de sal eg\u00edpcio de alta qualidade Uma empresa eg\u00edpcia para o fabrico e produ\u00e7\u00e3o dos melhores tipos de sal de todos os tipos Contate-nos Sobre n\u00f3s A solu\u00e7\u00e3o certa adaptada ao seu mercado. View Sal para tratamento de \u00e1guas Sal natural especialmente fabricado para o tratamento de \u00e1guasView Sal Industrial Sal Industrial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-26885","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/pt-pt\/wp-json\/wp\/v2\/pages\/26885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=26885"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/pt-pt\/wp-json\/wp\/v2\/pages\/26885\/revisions"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=26885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}