{"id":28146,"date":"2025-01-05T16:04:44","date_gmt":"2025-01-05T14:04:44","guid":{"rendered":"https:\/\/uae.mosesexport.com\/moses-08-12-%d0%bc%d0%be%d1%80%d1%81%d0%ba%d0%b0%d1%8f-%d1%81%d0%be%d0%bb%d1%8c-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%b5%d0%b3%d0%be-%d0%bf%d0%be%d0%bc%d0%be%d0%bb%d0%b0\/"},"modified":"2025-11-26T14:07:15","modified_gmt":"2025-11-26T12:07:15","slug":"moses-08-12-%d0%bc%d0%be%d1%80%d1%81%d0%ba%d0%b0%d1%8f-%d1%81%d0%be%d0%bb%d1%8c-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%b5%d0%b3%d0%be-%d0%bf%d0%be%d0%bc%d0%be%d0%bb%d0%b0","status":"publish","type":"page","link":"https:\/\/uae.mosesexport.com\/ru\/%d1%81%d0%be%d0%bb%d1%8c\/%d1%81%d0%be%d0%bb%d1%8c-%d0%bf%d0%be-%d0%b2%d0%ba%d1%83%d1%81%d1%83\/moses-08-12-%d0%bc%d0%be%d1%80%d1%81%d0%ba%d0%b0%d1%8f-%d1%81%d0%be%d0%bb%d1%8c-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%b5%d0%b3%d0%be-%d0%bf%d0%be%d0%bc%d0%be%d0%bb%d0%b0\/","title":{"rendered":"MOSES\u00ae 0,8-1,2, \u043c\u043e\u0440\u0441\u043a\u0430\u044f \u0441\u043e\u043b\u044c \u0441\u0440\u0435\u0434\u043d\u0435\u0433\u043e \u043f\u043e\u043c\u043e\u043b\u0430"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"28146\" class=\"elementor elementor-28146 elementor-17437\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d1ea74 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4d1ea74\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-915180a animated-fast elementor-invisible\" data-id=\"915180a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbe41e4 start elementor-widget elementor-widget-wdt-heading\" data-id=\"fbe41e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-fbe41e4\"><div class=\"wdt-heading-content-wrapper\">MOSES\u00ae 0.8-1.2, medium fine salt\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8731c9d wdt-cus-grid-img-counter\" data-wdt-settings=\"{&quot;id&quot;:&quot;8731c9d&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"8731c9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e66d2c elementor-widget elementor-widget-image\" data-id=\"1e66d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5aed05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5aed05\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b1f3a1\" data-id=\"3b1f3a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a288b05 elementor-widget elementor-widget-spacer\" data-id=\"a288b05\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e64d6cf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e64d6cf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9c31b5\" data-wdt-settings=\"{&quot;id&quot;:&quot;e9c31b5&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"e9c31b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70820af start elementor-widget__width-initial elementor-widget elementor-widget-wdt-heading\" data-id=\"70820af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-70820af\"><div class=\"wdt-heading-content-wrapper\">Pure grain with broad functionality. Scores particularly well as a topping for snacks.\nAs topping salt for bagels, pretzels and salt sticks\nProduction of snacks\nUse in fish smokehouses or as decorative salt with dried fish\nGut processing\nSeasoning mixes\nFish and meat production Also available in bulk (by silo wagon) without additives. Non-caking.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29ac456 animated-fast elementor-invisible\" data-id=\"29ac456\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2a189d start wdt-cus-about1-iconbox wdt-cus-about1-iconbox-top elementor-widget__width-initial elementor-widget elementor-widget-wdt-icon-box\" data-id=\"b2a189d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;icon_default_normal_background_background&quot;:&quot;classic&quot;,&quot;icon_default_normal_background_color&quot;:&quot;#EDEDED&quot;,&quot;icon_default_hover_background_background&quot;:&quot;classic&quot;,&quot;icon_default_hover_background_color&quot;:&quot;#54595F&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;1&quot;,&quot;columns_mobile&quot;:1,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder wdt-content-item-holder wdt-column-holder wdt-rc-template-ico-content-aside\" id=\"wdt-icon-box-b2a189d\" data-settings=\"\"><div class=\"wdt-column-wrapper wdt-column-gap-custom \" data-column-settings=\"\" data-module-id=\"wdt-module-id-b2a189d\" id=\"wdt-module-id-b2a189d\"><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>The very highest food grade quality (99.8% NaCl)<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Quite literally every single grain is checked for purity.\n\n\n\n<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Natural product<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Highlight the natural properties of sea salt in your customer communications.\n\n\n\n<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Rich in minerals and trace elements<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Body essentials.\n\n\n\n<\/div><\/div><\/div><\/div><div class=\"wdt-column\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Salt without E-numbers<\/h5><\/div><div class=\"wdt-content-separator separator-1\"><span><\/span><\/div><div class=\"wdt-content-description\">Perfect for your conventional as well as organic production lines.\n\n\n\n<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e59dfe3 e-flex e-con-boxed e-con e-parent\" data-id=\"e59dfe3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-504ebff wdt-cus-our-policy wdt-cus-home2-iconbox center elementor-widget elementor-widget-wdt-icon-box\" data-id=\"504ebff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;item_normal_background_background&quot;:&quot;classic&quot;,&quot;item_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-icon-box-holder  wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-icon-box-504ebff\" data-id=\"504ebff\" data-settings=\"\"><div class=\"wdt-icon-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;false&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;&quot;,&quot;overflow_opacity&quot;:&quot;&quot;,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:30,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:3,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:30,&quot;mobile&quot;:30,&quot;tablet&quot;:30}}\" id=\"wdt-icon-box-swiper-504ebff\"><div class=\"wdt-icon-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Grain size<\/h5><\/div><div class=\"wdt-content-description\">800-1600 \u00b5m\n\n\n\n\n\n\n<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Types Of Raw Materials<\/h5><\/div><div class=\"wdt-content-description\">Sea salt - Rock salt<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Packaging<\/h5><\/div><div class=\"wdt-content-description\">5KG - 10 KG - 20 KG - 25KG  (BAGS)\n1000KG - 1250KG - 1500KG (JAMBO)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Additives<\/h5><\/div><div class=\"wdt-content-description\">Available without additives\n(Available with potassium iodate (iodine)<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Storage<\/h5><\/div><div class=\"wdt-content-description\">Store in a dry place<\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5>Shipment<\/h5><\/div><div class=\"wdt-content-description\">Trailer truck<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-504ebff\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6507ca4 wdt-no-full-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6507ca4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;wdt_bg_position&quot;:&quot;center left&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2c3d58 animated-fast elementor-invisible\" data-id=\"b2c3d58\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;100&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9caafc9 elementor-widget__width-initial center elementor-widget elementor-widget-wdt-heading\" data-id=\"9caafc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-9caafc9\"><div class=\"wdt-heading-content-wrapper\">Similar Items<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ba9267b e-flex e-con-boxed e-con e-parent\" data-id=\"ba9267b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b9dc89 wdt-cus-services-imgbox animated-fast elementor-widget__width-initial center elementor-invisible elementor-widget elementor-widget-wdt-image-box\" data-id=\"0b9dc89\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_opts&quot;:&quot;6&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;100&quot;,&quot;marquee_class&quot;:&quot;yes&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;dpt&quot;,&quot;size&quot;:13,&quot;sizes&quot;:[]},&quot;overflow_type&quot;:&quot;right&quot;,&quot;carousel_dots_default_normal_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_normal_background_color&quot;:&quot;#6EC1E4&quot;,&quot;carousel_dots_default_hover_background_background&quot;:&quot;classic&quot;,&quot;carousel_dots_default_hover_background_color&quot;:&quot;#FFC527&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show_opts_tablet&quot;:2,&quot;slides_to_show_opts_mobile&quot;:1,&quot;slides_to_scroll_opts&quot;:&quot;single&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:300,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;carousel_arrows_prev_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_prev_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_vertical_top_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;carousel_arrows_next_arrow_horizontal_left_indent_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-image-box-holder wdt-marquee-wrapper wdt-content-item-holder wdt-carousel-holder wdt-rc-template-custom-template\" id=\"wdt-image-box-0b9dc89\" data-id=\"0b9dc89\" data-settings=\"{&quot;enable_popup&quot;:&quot;&quot;,&quot;enable_hover_class&quot;:&quot;&quot;}\"><div class=\"wdt-image-box-container swiper\" data-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;default&quot;,&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:1,&quot;arrows&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;mouse_wheel_scroll&quot;:&quot;&quot;,&quot;speed&quot;:300,&quot;autoplay&quot;:&quot;&quot;,&quot;autoplay_speed&quot;:null,&quot;autoplay_direction&quot;:null,&quot;allow_touch&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;centered_slides&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:null,&quot;overflow_type&quot;:&quot;right&quot;,&quot;overflow_opacity&quot;:null,&quot;unequal_height_compatability&quot;:null,&quot;gap&quot;:13,&quot;responsive&quot;:[{&quot;breakpoint&quot;:319,&quot;toshow&quot;:1,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:768,&quot;toshow&quot;:2,&quot;toscroll&quot;:1},{&quot;breakpoint&quot;:1025,&quot;toshow&quot;:6,&quot;toscroll&quot;:1}],&quot;space_between_gaps&quot;:{&quot;desktop&quot;:13,&quot;mobile&quot;:13,&quot;tablet&quot;:13}}\" id=\"wdt-image-box-swiper-0b9dc89\"><div class=\"wdt-image-box-wrapper swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-0-2-extra-fine-sea-salt\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png\" class=\"attachment-full size-full wp-image-17414\" alt=\"MOSES\u00ae 0.8-1, medium fine salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-0-2-extra-fine-sea-salt\/\">MOSES\u00ae 0-0.2, extra fine salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-2-0-8-fine-sea-salt\/\"rel=\"nofollow\" ><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png\" class=\"attachment-full size-full wp-image-17414\" alt=\"MOSES\u00ae 0.8-1, medium fine salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.2-0.8-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-2-0-8-fine-sea-salt\/\"rel=\"nofollow\" >MOSES\u00ae 0.2-0.8, fine salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-1-fine-sea-salt-2\/\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1.png\" class=\"attachment-full size-full wp-image-17418\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0-1-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-1-fine-sea-salt-2\/\">MOSES\u00ae 0-1, fine salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-2-medium-fine-sea-salt\/\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2.png\" class=\"attachment-full size-full wp-image-17415\" alt=\"MOSES\u00ae 1-2, medium coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/0.8-1.2-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-0-8-1-2-medium-fine-sea-salt\/\">MOSES\u00ae 0.8-1.2, medium fine salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-2-medium-coarse-sea-salt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2.png\" class=\"attachment-full size-full wp-image-17419\" alt=\"\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-2-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-2-medium-coarse-sea-salt\/\">MOSES\u00ae 1-2, medium coarse salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-3-medium-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3.png\" class=\"attachment-full size-full wp-image-17420\" alt=\"MOSES\u00ae 1-3, medium coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-3-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-3-medium-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 1-3, medium coarse salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-1-4-coarse-sea-salt\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4.png\" class=\"attachment-full size-full wp-image-17421\" alt=\"MOSES\u00ae 1-4, coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/1-4-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-1-4-coarse-sea-salt\/\"rel=\"nofollow\" >MOSES\u00ae 1-4, coarse salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-2-4-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png\" class=\"attachment-full size-full wp-image-17422\" alt=\"MOSES\u00ae 2-4, coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/2-4-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-2-4-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 2-4, coarse salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-4-6-extra-coarse-sea-salt-2\/\"rel=\"nofollow\" ><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6.png\" class=\"attachment-full size-full wp-image-17423\" alt=\"MOSES\u00ae 4-6, extra coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-6-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-4-6-extra-coarse-sea-salt-2\/\"rel=\"nofollow\" >MOSES\u00ae 4-6, extra coarse sea salt<\/a><\/h5><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"wdt-content-item\"><div class=\"wdt-content-media-group\"><div class=\"wdt-content-image-wrapper \"><div class=\"wdt-content-image\"><a href=\"https:\/\/uae.mosesexport.com\/moses-4-15-extra-coarse-sea-salt-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15.png\" class=\"attachment-full size-full wp-image-17424\" alt=\"MOSES\u00ae 4-15, extra coarse salt\" srcset=\"https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15.png 800w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-600x450.png 600w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-300x225.png 300w, https:\/\/uae.mosesexport.com\/wp-content\/uploads\/2025\/01\/4-15-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\"><\/a><\/div><\/div><\/div><div class=\"wdt-content-detail-group\"><div class=\"wdt-content-title\"><h5><a href=\"https:\/\/uae.mosesexport.com\/moses-4-15-extra-coarse-sea-salt-2\/\">MOSES\u00ae 4-15, extra coarse sea salt<\/a><\/h5><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wdt-carousel-pagination-wrapper\"><div class=\"wdt-swiper-pagination wdt-swiper-pagination-0b9dc89\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MOSES\u00ae 0.8-1.2, medium fine salt Pure grain with broad functionality. Scores particularly well as a topping for snacks. As topping salt for bagels, pretzels and salt sticks Production of snacks Use in fish smokehouses or as decorative salt with dried fish Gut processing Seasoning mixes Fish and meat production Also available in bulk (by silo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32892,"parent":29085,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-28146","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/pages\/28146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/comments?post=28146"}],"version-history":[{"count":0,"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/pages\/28146\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/pages\/29085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/media\/32892"}],"wp:attachment":[{"href":"https:\/\/uae.mosesexport.com\/ru\/wp-json\/wp\/v2\/media?parent=28146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}